{"id":18263,"date":"2020-04-27T09:51:39","date_gmt":"2020-04-27T09:51:39","guid":{"rendered":"https:\/\/stg.visualarq.com\/?post_type=tip&#038;p=18263"},"modified":"2020-09-19T18:25:13","modified_gmt":"2020-09-19T18:25:13","slug":"why-some-walls-dont-join","status":"publish","type":"tip","link":"https:\/\/stg.visualarq.com\/de\/support\/tip\/why-some-walls-dont-join\/","title":{"rendered":"Warum lassen sich einige W\u00e4nde nicht verbinden?"},"content":{"rendered":"<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-1-1.png\" alt=\"Zwei Modelle mit Problemen bei sich schneidenden W\u00e4nden.\" width=\"1000\" height=\"450\" class=\"aligncenter size-full wp-image-18296\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-1-1.png 1000w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-1-1-980x441.png 980w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-1-1-480x216.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/>\r\n<p>Einer der Hauptgr\u00fcnde, warum W\u00e4nde sich nicht richtig verbinden lassen, liegt darin, dass mindestens eine dieser W\u00e4nde verl\u00e4ngert ist.<\/p>\r\n<p>Aus Verl\u00e4ngerungen entstehende Wandseiten k\u00f6nnen keine Schnitte mit anderen W\u00e4nden aufl\u00f6sen.<\/p>\r\n<h3>Warum l\u00f6sen Wandverl\u00e4ngerungen keine Schnitte auf?<\/h3>\r\n<p>Der Grund ist, dass der Befehl zur Wandverl\u00e4ngerung (vaWandVerl\u00e4ngern) zur Nachbearbeitung dient nachdem die Schnitte bereits aufgel\u00f6st wurden, d.h. die Wand wird lediglich extrudiert oder getrimmt. Tats\u00e4chlich bleibt der H\u00f6henwert einer Wand nach ihrer Verl\u00e4ngerung gleich.<\/p>\r\n<h3>L\u00f6sungen<\/h3>\r\n<p>Im untenstehenden Beispiel ist die tats\u00e4chliche H\u00f6he von Wand 1 bis an die rote Linie eingestellt. Da sie aber bis ans Dach verl\u00e4ngert wurde, konnte die restliche \u00dcberschneidung mit Wand 2 nicht aufgel\u00f6st werden.<\/p>\r\n<p>Die L\u00f6sung besteht darin, die H\u00f6he von Wand 1 mindestens wie die von Wand 2 einzustellen.<\/p>\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-2-1.png\" alt=\"Das selbe Modell, links mit einem Problem bei der Wand\u00fcberschneidung und rechts ohne dieses Problem.\" width=\"950\" height=\"400\" class=\"aligncenter size-full wp-image-18303\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-2-1.png 950w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-2-1-480x202.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 950px, 100vw\" \/>\r\n<p>In diesem anderen Beispiel wurde Wand 3 bis an das h\u00f6here Dach verl\u00e4ngert, woraus eine neue Seite entstand, die nicht zur Aufl\u00f6sung der \u00dcberschneidung mit Wand 4 in der Lage ist. Das Problem w\u00fcrde auch weiterhin bestehen, wenn Wand 3 von vorneherein h\u00f6her w\u00e4re und abw\u00e4rts, zum niedrigeren Dach hin, verl\u00e4ngert w\u00fcrde.<\/p>\r\n<p>In diesem Fall besteht die L\u00f6sung darin, Wand 3 in drei Teile aufzuteilen, zwei f\u00fcr das untere Dach und einen f\u00fcr das h\u00f6here. Somit wird es m\u00f6glich, die H\u00f6he jeder Wand so nahe wie m\u00f6glich an ihr Dach heranzuf\u00fchren und die Verl\u00e4ngerung nur zur Abschr\u00e4gung ihrer Oberseite zu verwenden.<\/p>\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-3.png\" alt=\"Das selbe Modell, links mit einem Problem bei der Wand\u00fcberschneidung und rechts ohne dieses Problem.\" width=\"1000\" height=\"450\" class=\"aligncenter size-full wp-image-18310\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-3.png 1000w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-3-980x441.png 980w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-3-480x216.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/>\r\n<h3>Zusammenfassung<\/h3>\r\n<ul>\r\n<li>Erzeugen Sie W\u00e4nde von vorneherein mit der richtigen H\u00f6he, so nahe wie m\u00f6glich an der ben\u00f6tigten H\u00f6he.<\/li>\r\n<li>Verwenden Sie die Wandverl\u00e4ngerung m\u00f6glichst nur dann, wenn Sie nicht horizontale Ober- oder Unterseiten ben\u00f6tigen.<\/li>\r\n<li>Verwenden Sie nach M\u00f6glichkeit f\u00fcr jede H\u00f6he eine andere Wand, oder anders ausgedr\u00fcckt, vermeiden Sie das Verl\u00e4ngern einer Wand zu mehr als einem Objekt hin, wenn diese sich auf verschiedenen H\u00f6hen befinden.<\/li>\r\n<\/ul>\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-4.png\" alt=\"Zwei Modelle ohne Probleme mit sich schneidenden W\u00e4nden.\" width=\"1000\" height=\"450\" class=\"aligncenter size-full wp-image-18317\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-4.png 1000w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-4-980x441.png 980w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2020\/04\/walls-intersection-tip-4-480x216.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/>","protected":false},"featured_media":2092,"parent":0,"menu_order":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tipgroup":[162],"class_list":["post-18263","tip","type-tip","status-publish","has-post-thumbnail","hentry","tipgroup-walls-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Warum lassen sich einige W\u00e4nde nicht verbinden? - VisualARQ<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Warum lassen sich einige W\u00e4nde nicht verbinden? - VisualARQ\" \/>\n<meta property=\"og:description\" content=\"Einer der Hauptgr\u00fcnde, warum W\u00e4nde sich nicht richtig verbinden lassen, liegt darin, dass mindestens eine dieser W\u00e4nde verl\u00e4ngert ist. Aus Verl\u00e4ngerungen entstehende Wandseiten k\u00f6nnen keine Schnitte mit anderen W\u00e4nden aufl\u00f6sen. Warum l\u00f6sen Wandverl\u00e4ngerungen keine Schnitte auf? Der Grund ist, dass der Befehl zur Wandverl\u00e4ngerung (vaWandVerl\u00e4ngern) zur Nachbearbeitung dient nachdem die Schnitte bereits aufgel\u00f6st wurden, d.h. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stg.visualarq.com\/de\/support\/tip\/why-some-walls-dont-join\/\" \/>\n<meta property=\"og:site_name\" content=\"VisualARQ\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/visualarq\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-19T18:25:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/Tangent-walls-joint.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"452\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@VisualARQ\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/de\\\/support\\\/tip\\\/why-some-walls-dont-join\\\/\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/de\\\/support\\\/tip\\\/why-some-walls-dont-join\\\/\",\"name\":\"Warum lassen sich einige W\u00e4nde nicht verbinden? - VisualARQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/de\\\/support\\\/tip\\\/why-some-walls-dont-join\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/de\\\/support\\\/tip\\\/why-some-walls-dont-join\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Tangent-walls-joint.png\",\"datePublished\":\"2020-04-27T09:51:39+00:00\",\"dateModified\":\"2020-09-19T18:25:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/de\\\/support\\\/tip\\\/why-some-walls-dont-join\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stg.visualarq.com\\\/de\\\/support\\\/tip\\\/why-some-walls-dont-join\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/de\\\/support\\\/tip\\\/why-some-walls-dont-join\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Tangent-walls-joint.png\",\"contentUrl\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Tangent-walls-joint.png\",\"width\":750,\"height\":452},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/de\\\/support\\\/tip\\\/why-some-walls-dont-join\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tips\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/de\\\/support\\\/tip\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Warum lassen sich einige W\u00e4nde nicht verbinden?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/de\\\/\",\"name\":\"VisualARQ\",\"description\":\"Flexible BIM for Rhino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stg.visualarq.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Warum lassen sich einige W\u00e4nde nicht verbinden? - VisualARQ","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Warum lassen sich einige W\u00e4nde nicht verbinden? - VisualARQ","og_description":"Einer der Hauptgr\u00fcnde, warum W\u00e4nde sich nicht richtig verbinden lassen, liegt darin, dass mindestens eine dieser W\u00e4nde verl\u00e4ngert ist. Aus Verl\u00e4ngerungen entstehende Wandseiten k\u00f6nnen keine Schnitte mit anderen W\u00e4nden aufl\u00f6sen. Warum l\u00f6sen Wandverl\u00e4ngerungen keine Schnitte auf? Der Grund ist, dass der Befehl zur Wandverl\u00e4ngerung (vaWandVerl\u00e4ngern) zur Nachbearbeitung dient nachdem die Schnitte bereits aufgel\u00f6st wurden, d.h. [&hellip;]","og_url":"https:\/\/stg.visualarq.com\/de\/support\/tip\/why-some-walls-dont-join\/","og_site_name":"VisualARQ","article_publisher":"https:\/\/www.facebook.com\/visualarq","article_modified_time":"2020-09-19T18:25:13+00:00","og_image":[{"width":750,"height":452,"url":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/Tangent-walls-joint.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@VisualARQ","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stg.visualarq.com\/de\/support\/tip\/why-some-walls-dont-join\/","url":"https:\/\/stg.visualarq.com\/de\/support\/tip\/why-some-walls-dont-join\/","name":"Warum lassen sich einige W\u00e4nde nicht verbinden? - VisualARQ","isPartOf":{"@id":"https:\/\/stg.visualarq.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stg.visualarq.com\/de\/support\/tip\/why-some-walls-dont-join\/#primaryimage"},"image":{"@id":"https:\/\/stg.visualarq.com\/de\/support\/tip\/why-some-walls-dont-join\/#primaryimage"},"thumbnailUrl":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/Tangent-walls-joint.png","datePublished":"2020-04-27T09:51:39+00:00","dateModified":"2020-09-19T18:25:13+00:00","breadcrumb":{"@id":"https:\/\/stg.visualarq.com\/de\/support\/tip\/why-some-walls-dont-join\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stg.visualarq.com\/de\/support\/tip\/why-some-walls-dont-join\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stg.visualarq.com\/de\/support\/tip\/why-some-walls-dont-join\/#primaryimage","url":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/Tangent-walls-joint.png","contentUrl":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/Tangent-walls-joint.png","width":750,"height":452},{"@type":"BreadcrumbList","@id":"https:\/\/stg.visualarq.com\/de\/support\/tip\/why-some-walls-dont-join\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stg.visualarq.com\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Tips","item":"https:\/\/stg.visualarq.com\/de\/support\/tip\/"},{"@type":"ListItem","position":3,"name":"Warum lassen sich einige W\u00e4nde nicht verbinden?"}]},{"@type":"WebSite","@id":"https:\/\/stg.visualarq.com\/de\/#website","url":"https:\/\/stg.visualarq.com\/de\/","name":"VisualARQ","description":"Flexible BIM for Rhino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stg.visualarq.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/stg.visualarq.com\/de\/wp-json\/wp\/v2\/tip\/18263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.visualarq.com\/de\/wp-json\/wp\/v2\/tip"}],"about":[{"href":"https:\/\/stg.visualarq.com\/de\/wp-json\/wp\/v2\/types\/tip"}],"version-history":[{"count":0,"href":"https:\/\/stg.visualarq.com\/de\/wp-json\/wp\/v2\/tip\/18263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.visualarq.com\/de\/wp-json\/wp\/v2\/media\/2092"}],"wp:attachment":[{"href":"https:\/\/stg.visualarq.com\/de\/wp-json\/wp\/v2\/media?parent=18263"}],"wp:term":[{"taxonomy":"tipgroup","embeddable":true,"href":"https:\/\/stg.visualarq.com\/de\/wp-json\/wp\/v2\/tipgroup?post=18263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}