{"id":8098,"date":"2014-07-29T00:00:00","date_gmt":"2014-07-29T00:00:00","guid":{"rendered":"https:\/\/stg.visualarq.com\/2014\/07\/29\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/"},"modified":"2014-07-29T00:00:00","modified_gmt":"2014-07-29T00:00:00","slug":"el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico","status":"publish","type":"post","link":"https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/","title":{"rendered":"El \u00e9xito de un par\u00e1sito arquitect\u00f3nico en un legado prehist\u00f3rico"},"content":{"rendered":"Pensamos en el uso de programas arquitect\u00f3nicos como Rhino y nos vienen a la mente los trabajos de Zaha Hadid o Norman Foster. Pero Rhino va m\u00e1s all\u00e1 de descomunales proyectos o de la complejidad param\u00e9trica o NURBS. En este blog, queremos ampliar la mirada.\n\nCuando un arquitecto o ingeniero se plantea comparar los mejores programas para su trabajo, se decanta por <a href=\"https:\/\/stg.visualarq.com\/es\/info\/what-is-rhino\/\">Rhino<\/a> cuando necesita libertad de trazo, un modelado preciso, curvas complejas\u2026 pero sus posibilidades son muchas otras.\n\nSi, adem\u00e1s, a\u00f1adimos una herramienta como VisualARQ, la tecnolog\u00eda estar\u00e1 al servicio de su creatividad y no al rev\u00e9s. Para cualquier tama\u00f1o de proyecto.\n\n<div id=\"attachment_2638\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2638\" class=\"size-full wp-image-2638\" alt=\"VisualARQ, el software arquitect\u00f3nico de forma libre, analiza el dise\u00f1o del Museo de Monteagudo\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/VisualARQ-Free-form-architectural-software-analyzes-design-Museum-Monteagudo.jpg\" width=\"600\" height=\"463\" \/><p id=\"caption-attachment-2638\" class=\"wp-caption-text\">VisualARQ, el software arquitect\u00f3nico de forma libre, analiza el dise\u00f1o del Museo de Monteagudo. Imagen por David Frutos<\/p><\/div>\n\nVolvamos al principio. \u00bfGrandes construcciones? No necesariamente. Ni siquiera en el nombre o en el concepto. \u00bfCu\u00e1ntos t\u00edtulos grandilocuentes conoces aplicados a proyectos? Pueden ser adjetivos brillantes, denominaciones sugerentes, m\u00edsticas o alusiones ex\u00f3ticas. \u00bfA qui\u00e9n no le gusta contemplar su obra bajo un t\u00edtulo que exprese su sofisticaci\u00f3n?\n\n<div id=\"attachment_2639\" style=\"width: 310px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2639\" class=\"size-full wp-image-2639\" alt=\"Hormig\u00f3n y metal grabado. Solidez y ligereza.\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/Concrete-metal-engraving-Solidity-lightness.jpg\" width=\"300\" height=\"397\" \/><p id=\"caption-attachment-2639\" class=\"wp-caption-text\">Hormig\u00f3n y metal grabado. Solidez y ligereza. . Imagen por David Frutos<\/p><\/div>\n\nPues bien, hay opciones alternativas: el estudio con oficina en Madrid de <a href=\"https:\/\/www.amann-canovas-maruri.es\/\">Amann, C\u00e1novas y Maruri<\/a> habla de su proyecto para el <a href=\"https:\/\/www.monteagudo.info\/web\/instalaciones-y-servicios\/centro-visitantes-monteagudo\/\">Centro de Visitantes del Museo de Monteagudo<\/a> diciendo \u201cEste edificio es, sin duda, un par\u00e1sito\u201d.\n\nQu\u00e9 alivio. Un par\u00e1sito en el mejor de los sentidos, el de m\u00edmesis y adaptaci\u00f3n. Un intercambio fruct\u00edfero de energ\u00eda.\n\n<a href=\"https:\/\/es.wikipedia.org\/wiki\/Monteagudo_%28Murcia%29\">Monteagudo <\/a>es una peque\u00f1a localidad de la provincia de Murcia, en Espa\u00f1a. No fue dif\u00edcil elegir la mejor ubicaci\u00f3n para un nuevo museo, simplemente ten\u00edan que seguir la corriente de la historia local. Una colina cercana es la representaci\u00f3n f\u00edsica de la historia del pueblo. Por su privilegiada posici\u00f3n fue elegida por los sucesivos habitantes de la comarca \u00a1desde la prehistoria! Existen restos de un poblado arg\u00e1rico de la Edad del Bronce fechado 2.000 a\u00f1os a.C., un poblado ibero del s. IV a. C, un yacimiento romano del s. I d.C, de un poblado \u00e1rabe, pervive una ermita cristiana y los restos de un castillo del a\u00f1o 1.000.\n\n<div id=\"attachment_2640\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2640\" class=\"size-full wp-image-2640\" alt=\"Restos arqueol\u00f3gicos integrados en el nuevo edificio \" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/Archaeological-remains-integrated-New-building.jpg\" width=\"600\" height=\"400\" \/><p id=\"caption-attachment-2640\" class=\"wp-caption-text\">Restos arqueol\u00f3gicos integrados en el nuevo edificio. Imagen por www.monteagudo.info<\/p><\/div>\n\nImaginen por un momento que son arquitectos y reciben el encargo de crear una obra que, con el tiempo, dejar\u00e1 su rastro con estos ilustres precedentes. Historia con may\u00fasculas. Los afortunados fueron Atxu Amann, Andr\u00e9s C\u00e1novas y Nicol\u00e1s Maruri, quienes emplearon el software Rhino.\n\nEl Centro de Visitantes est\u00e1 justamente d\u00f3nde existieron el poblado prehist\u00f3rico y el asentamiento romano. Por un lado, se deben conservar los restos y permitir su estudio. Por otro, debe adherirse a la piel de la monta\u00f1a coronada por un castillo y una ermita y convivir con ellos. Cuando se divise desde la cima o desde las torres del castillo, el museo debe ser un relieve m\u00e1s.\n\n<div id=\"attachment_2641\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2641\" class=\"size-full wp-image-2641\" alt=\"Muestras de la construcci\u00f3n realizada con el software Rhino \" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/construction-designed-Rhino-software.jpg\" width=\"600\" height=\"308\" \/><p id=\"caption-attachment-2641\" class=\"wp-caption-text\">Muestras de la construcci\u00f3n realizada con el software Rhino. Imagen por David Frutos<\/p><\/div>\n\nLa orograf\u00eda del terreno condiciona toda construcci\u00f3n. En este caso, dado que se trata de un edificio que recibir\u00e1 visitas, se ha optado por las rampas. Doble ventaja: favorecen el acceso de todo tipo de visitantes y al mismo tiempo hacen que los vol\u00famenes del edificio encajen en el entorno. La construcci\u00f3n tiene forma de \u201cU\u201d, dejando en el centro una capilla barroca.\n\n<div id=\"attachment_2642\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2642\" class=\"size-full wp-image-2642\" alt=\"El dise\u00f1o del moderno edificio deja en su centro una capilla barroca\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/design-modern-building-center-baroque-chapel.jpg\" width=\"600\" height=\"316\" \/><p id=\"caption-attachment-2642\" class=\"wp-caption-text\">El dise\u00f1o del moderno edificio deja en su centro una capilla barroca. Imagen por David Frutos<\/p><\/div>\n\nSalvada la cuesti\u00f3n de la forma, \u00bfqu\u00e9 hacemos con el revestimiento? No se ha elegido la piedra que se mimetice con la ladera de la monta\u00f1a. Este par\u00e1sito tiene piel de metal, con un dise\u00f1o vegetal que la cubre por completo, inspirado en la naturaleza de los alrededores.\n\n<div id=\"attachment_2643\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2643\" class=\"size-full wp-image-2643\" alt=\"El revestimiento met\u00e1lico est\u00e1 inspirado en las formas de la naturaleza de los alrededores\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/Metal-coating-inspired-forms-surrounding-nature.jpg\" width=\"600\" height=\"266\" \/><p id=\"caption-attachment-2643\" class=\"wp-caption-text\">El revestimiento met\u00e1lico est\u00e1 inspirado en las formas de la naturaleza de los alrededores. Imagen por David Frutos y Zeisterre<\/p><\/div>\n\nLa planta inferior se ha pensado como un elemento abierto, como un refugio temporal. Los autores del proyecto han creado un edificio urbano que queda abierto a los vecinos y se convierte en un refugio a la sombra bajo el inclemente sol de Murcia. Sus muros son de hormig\u00f3n visto y cuenta con paneles movibles realizados en metal.\n\n<div id=\"attachment_2644\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2644\" class=\"size-full wp-image-2644\" alt=\"La entrada del edificio queda integrada en la trama urbana\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/entrance-building-integrated-Into-urban-fabric.jpg\" width=\"600\" height=\"302\" \/><p id=\"caption-attachment-2644\" class=\"wp-caption-text\">La entrada del edificio queda integrada en la trama urbana. Imagen por David Frutos<\/p><\/div>\n\nSi quieres acceder a las exposiciones temporales, debes ascender a la planta superior donde se encuentran las salas. A trav\u00e9s de las ventanas, contemplas la naturaleza y el castillo. Su estructura met\u00e1lica la forma un panel de m\u00faltiples hojas selladas con impermeabilizaci\u00f3n en caliente. El caparaz\u00f3n de este peculiar par\u00e1sito es un recubrimiento de acero cort\u00e9n perforado con unos motivos que recuerdan la vegetaci\u00f3n. A trav\u00e9s de ellos, la luz llega tamizada al interior.\n\n<div id=\"attachment_2645\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2645\" class=\"size-full wp-image-2645\" alt=\"Acceso a la zona de las exposiciones temporales del museo\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/Access-area-temporary-exhibitions-Museum.jpg\" width=\"600\" height=\"268\" \/><p id=\"caption-attachment-2645\" class=\"wp-caption-text\">Acceso a la zona de las exposiciones temporales del museo. Imagen por David Frutos<\/p><\/div>\n\nLas celos\u00edas met\u00e1licas son claramente contempor\u00e1neas por su material pero, si pensamos en la tradici\u00f3n arquitect\u00f3nica, es inevitable pensar en las celos\u00edas \u00e1rabes.\n\nLa l\u00e1mina del agua del interior nos lleva con la imaginaci\u00f3n a las habituales en la arquitectura \u00e1rabe.\n\n<div id=\"attachment_2647\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2647\" class=\"size-full wp-image-2647\" alt=\"Paralelismo entre el uso del agua en la arquitectura contempor\u00e1nea y en la \u00e1rabe tradicional\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/Parallelism-use-water-contemporary-architecture-traditional-Arabic-Alhambra.jpg\" width=\"600\" height=\"216\" \/><p id=\"caption-attachment-2647\" class=\"wp-caption-text\">Paralelismo entre el uso del agua en la arquitectura contempor\u00e1nea y en la \u00e1rabe tradicional. Imagen por David Frutos y Zeisterre<\/p><\/div>\n\nHace m\u00e1s de 700 a\u00f1os, a trav\u00e9s de unas celos\u00edas \u00e1rabes, de madera o piedra, se pod\u00eda contemplar esta colina. Hoy, siglos despu\u00e9s, vislumbramos a trav\u00e9s de otra celos\u00eda de metal el mismo paisaje. En nuestra contemplaci\u00f3n hay algo m\u00e1s, este Museo nos permitir\u00e1 acercarnos a los antiguos yacimientos y observar los restos de la forma de vida de quienes nos precedieron.\n\nEn esta colina de Murcia adquirimos la conciencia de que no somos los primeros. Confiemos en que tampoco los \u00faltimos. El Centro de Visitantes del Museo de Monteagudo, nuestra huella.\n\n<div id=\"attachment_2648\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2648\" class=\"size-full wp-image-2648\" alt=\"En la cima de la colina se divisan los restos del castillo de Monteagudo, Murcia\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/remains-Monteagudo-castle-seen-Museum.jpg\" width=\"600\" height=\"320\" \/><p id=\"caption-attachment-2648\" class=\"wp-caption-text\">En la cima de la colina se divisan los restos del castillo de Monteagudo, Murcia. Image por David Frutos<\/p><\/div>\n<ul>\n\t<li>Fuente: Estudio Amann, C\u00e1novas y Maruri<\/li>\n\t<li>Arquitectos: Atxu Amann Alcocer, Andr\u00e9s C\u00e1novas Alcaraz, Nicol\u00e1s Maruri Gonz\u00e1lez de Mendoza<\/li>\n\t<li>Arquitecto T\u00e9cnico: Rafael Checa<\/li>\n\t<li>Ubicaci\u00f3n: San Cayetano Square. Monteagudo. Murcia (Espa\u00f1a)<\/li>\n<\/ul>\n<em>(Art\u00edculo por\u00a0<a href=\"https:\/\/goo.gl\/H15TC2\">M.A. N\u00fa\u00f1ez<\/a>)<\/em>","protected":false},"excerpt":{"rendered":"<p>Pensamos en el uso de programas arquitect\u00f3nicos como Rhino y nos vienen a la mente los trabajos de Zaha Hadid o Norman Foster. Pero Rhino va m\u00e1s all\u00e1 de descomunales proyectos o de la complejidad param\u00e9trica o NURBS. En este blog, queremos ampliar la mirada. Cuando un arquitecto o ingeniero se plantea comparar los mejores [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5385,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1741],"tags":[1331,1390],"class_list":["post-8098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","tag-projects-es","tag-visualarq-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El \u00e9xito de un par\u00e1sito arquitect\u00f3nico en un legado prehist\u00f3rico - VisualARQ<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El \u00e9xito de un par\u00e1sito arquitect\u00f3nico en un legado prehist\u00f3rico - VisualARQ\" \/>\n<meta property=\"og:description\" content=\"Pensamos en el uso de programas arquitect\u00f3nicos como Rhino y nos vienen a la mente los trabajos de Zaha Hadid o Norman Foster. Pero Rhino va m\u00e1s all\u00e1 de descomunales proyectos o de la complejidad param\u00e9trica o NURBS. En este blog, queremos ampliar la mirada. Cuando un arquitecto o ingeniero se plantea comparar los mejores [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/\" \/>\n<meta property=\"og:site_name\" content=\"VisualARQ\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/visualarq\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-29T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/remains-Monteagudo-castle-seen-Museum.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Enric Marqu\u00e8s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@VisualARQ\" \/>\n<meta name=\"twitter:site\" content=\"@VisualARQ\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enric Marqu\u00e8s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\\\/\"},\"author\":{\"name\":\"Enric Marqu\u00e8s\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/#\\\/schema\\\/person\\\/111feff82e1e02370fbd7e7622a5ff96\"},\"headline\":\"El \u00e9xito de un par\u00e1sito arquitect\u00f3nico en un legado prehist\u00f3rico\",\"datePublished\":\"2014-07-29T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\\\/\"},\"wordCount\":1172,\"image\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/remains-Monteagudo-castle-seen-Museum.jpg\",\"keywords\":[\"Proyectos\",\"VisualARQ\"],\"articleSection\":[\"Art\u00edculos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\\\/\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\\\/\",\"name\":\"El \u00e9xito de un par\u00e1sito arquitect\u00f3nico en un legado prehist\u00f3rico - VisualARQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/remains-Monteagudo-castle-seen-Museum.jpg\",\"datePublished\":\"2014-07-29T00:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/#\\\/schema\\\/person\\\/111feff82e1e02370fbd7e7622a5ff96\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/remains-Monteagudo-castle-seen-Museum.jpg\",\"contentUrl\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/remains-Monteagudo-castle-seen-Museum.jpg\",\"width\":600,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El \u00e9xito de un par\u00e1sito arquitect\u00f3nico en un legado prehist\u00f3rico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/\",\"name\":\"VisualARQ\",\"description\":\"Flexible BIM for Rhino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/#\\\/schema\\\/person\\\/111feff82e1e02370fbd7e7622a5ff96\",\"name\":\"Enric Marqu\u00e8s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a272864c4313b14c343ff6cf644878275ce78241431b1a13fee0f3efb785afae?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a272864c4313b14c343ff6cf644878275ce78241431b1a13fee0f3efb785afae?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a272864c4313b14c343ff6cf644878275ce78241431b1a13fee0f3efb785afae?s=96&d=mm&r=g\",\"caption\":\"Enric Marqu\u00e8s\"},\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/author\\\/enric\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El \u00e9xito de un par\u00e1sito arquitect\u00f3nico en un legado prehist\u00f3rico - VisualARQ","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"El \u00e9xito de un par\u00e1sito arquitect\u00f3nico en un legado prehist\u00f3rico - VisualARQ","og_description":"Pensamos en el uso de programas arquitect\u00f3nicos como Rhino y nos vienen a la mente los trabajos de Zaha Hadid o Norman Foster. Pero Rhino va m\u00e1s all\u00e1 de descomunales proyectos o de la complejidad param\u00e9trica o NURBS. En este blog, queremos ampliar la mirada. Cuando un arquitecto o ingeniero se plantea comparar los mejores [&hellip;]","og_url":"https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/","og_site_name":"VisualARQ","article_publisher":"https:\/\/www.facebook.com\/visualarq","article_published_time":"2014-07-29T00:00:00+00:00","og_image":[{"width":600,"height":320,"url":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/remains-Monteagudo-castle-seen-Museum.jpg","type":"image\/jpeg"}],"author":"Enric Marqu\u00e8s","twitter_card":"summary_large_image","twitter_creator":"@VisualARQ","twitter_site":"@VisualARQ","twitter_misc":{"Escrito por":"Enric Marqu\u00e8s","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/#article","isPartOf":{"@id":"https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/"},"author":{"name":"Enric Marqu\u00e8s","@id":"https:\/\/stg.visualarq.com\/es\/#\/schema\/person\/111feff82e1e02370fbd7e7622a5ff96"},"headline":"El \u00e9xito de un par\u00e1sito arquitect\u00f3nico en un legado prehist\u00f3rico","datePublished":"2014-07-29T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/"},"wordCount":1172,"image":{"@id":"https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/#primaryimage"},"thumbnailUrl":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/remains-Monteagudo-castle-seen-Museum.jpg","keywords":["Proyectos","VisualARQ"],"articleSection":["Art\u00edculos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/","url":"https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/","name":"El \u00e9xito de un par\u00e1sito arquitect\u00f3nico en un legado prehist\u00f3rico - VisualARQ","isPartOf":{"@id":"https:\/\/stg.visualarq.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/#primaryimage"},"image":{"@id":"https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/#primaryimage"},"thumbnailUrl":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/remains-Monteagudo-castle-seen-Museum.jpg","datePublished":"2014-07-29T00:00:00+00:00","author":{"@id":"https:\/\/stg.visualarq.com\/es\/#\/schema\/person\/111feff82e1e02370fbd7e7622a5ff96"},"breadcrumb":{"@id":"https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/#primaryimage","url":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/remains-Monteagudo-castle-seen-Museum.jpg","contentUrl":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/01\/remains-Monteagudo-castle-seen-Museum.jpg","width":600,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/stg.visualarq.com\/es\/el-exito-de-un-parasito-arquitectonico-en-un-legado-prehistorico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stg.visualarq.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"El \u00e9xito de un par\u00e1sito arquitect\u00f3nico en un legado prehist\u00f3rico"}]},{"@type":"WebSite","@id":"https:\/\/stg.visualarq.com\/es\/#website","url":"https:\/\/stg.visualarq.com\/es\/","name":"VisualARQ","description":"Flexible BIM for Rhino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stg.visualarq.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/stg.visualarq.com\/es\/#\/schema\/person\/111feff82e1e02370fbd7e7622a5ff96","name":"Enric Marqu\u00e8s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a272864c4313b14c343ff6cf644878275ce78241431b1a13fee0f3efb785afae?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a272864c4313b14c343ff6cf644878275ce78241431b1a13fee0f3efb785afae?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a272864c4313b14c343ff6cf644878275ce78241431b1a13fee0f3efb785afae?s=96&d=mm&r=g","caption":"Enric Marqu\u00e8s"},"url":"https:\/\/stg.visualarq.com\/es\/author\/enric\/"}]}},"_links":{"self":[{"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/posts\/8098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/comments?post=8098"}],"version-history":[{"count":0,"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/posts\/8098\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/media\/5385"}],"wp:attachment":[{"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/media?parent=8098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/categories?post=8098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/tags?post=8098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}