{"id":16491,"date":"2019-07-26T12:30:32","date_gmt":"2019-07-26T12:30:32","guid":{"rendered":"https:\/\/stg.visualarq.com\/?page_id=16491"},"modified":"2024-09-23T14:31:07","modified_gmt":"2024-09-23T14:31:07","slug":"annotations","status":"publish","type":"tutorial","link":"https:\/\/stg.visualarq.com\/es\/tutorial\/grasshopper-styles\/annotations\/","title":{"rendered":"Anotaciones"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Tutorial de estilos de anotaci\u00f3n de Grasshopper<\/h1>\n\n<figure class=\"wp-block-image alignright size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"231\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/07\/GHtoVAAnnotation-1-300x231.png\" alt=\"Comparaci&#xF3;n entre la anotaci&#xF3;n de Grasshopper de la izquierda y la anotaci&#xF3;n de VisualARQ de la derecha.\" class=\"wp-image-16590\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/07\/GHtoVAAnnotation-1-300x231.png 300w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/07\/GHtoVAAnnotation-1.png 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">En el siguiente ejemplo, crearemos un Estilo de anotaci\u00f3n param\u00e9trico a partir de una definici\u00f3n de Grasshopper.<\/p>\n\n<p class=\"wp-block-paragraph\">Los 3 pasos principales a seguir son los mismos que en cualquier otro estilo de Grasshopper:<\/p>\n\n<ol class=\"wp-block-list\">\n<li><strong><a href=\"#setup\">Configurar la definici\u00f3n de Grasshopper<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"#create\">Crear el estilo de anotaci\u00f3n de VisualARQ<\/a><\/strong><\/li>\n\n\n\n<li><strong><a href=\"#edit\">Insertar y editar el estilo de anotaci\u00f3n de Grasshopper<\/a><\/strong><\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"setup\">1. Configurar la definici\u00f3n de Grasshopper<\/h2>\n\n<p class=\"wp-block-paragraph\">Requisitos previos a tener en cuenta al crear una definici\u00f3n de Grasshopper para un estilo de anotaci\u00f3n de Grasshopper:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Las anotaciones en VisualARQ se crean desde un punto de inserci\u00f3n y un plano. Este punto de inserci\u00f3n en la definici\u00f3n de Grasshopper se mide desde el <strong>origen de coordenadas<\/strong> <strong>(0,0,0)<\/strong> del documento y por defecto corresponde al plano XY.<\/li>\n\n\n\n<li>Si el punto de inserci\u00f3n como par\u00e1metro de entrada se define como un plano, el objeto resultante podr\u00e1 colocarse en cualquier plano del espacio del modelo. En caso contrario, se situar\u00e1 siempre en el plano XY.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Descargue el archivo de Grasshopper que se utiliza en este tutorial <a href=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Elevation-mark-m.gh\">aqu\u00ed<\/a>.<\/p>\n\n<p class=\"wp-block-paragraph\">Escriba <code>Grasshopper<\/code>  en la l\u00ednea de comandos de Rhino para ejecutar Grasshopper.<\/p>\n\n<p class=\"wp-block-paragraph\">La definici\u00f3n de Grasshopper requiere algunos <strong>par\u00e1metros de entrada<\/strong> para definir las caracter\u00edsticas del nuevo objeto, y <strong>par\u00e1metros de salida<\/strong> para definir los componentes geom\u00e9tricos del objeto final. Algunos par\u00e1metros de salida pueden utilizarse para recuperar informaci\u00f3n del objeto creado. <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Input parameters (Parametros de entrada)<\/strong>: son los componentes que definir\u00e1n las caracter\u00edsticas del estilo de pilar resultante. Estos son los diferentes par\u00e1metros que podemos encontrar en esta definici\u00f3n:\n<ul class=\"wp-block-list\">\n<li><strong>Plane (Plano):<\/strong> especifica el punto base (y el plano) para la anotaci\u00f3n.<\/li>\n\n\n\n<li><strong>Hatch Pattern (Patr\u00f3n de trama):<\/strong> especifica el patr\u00f3n de trama para la anotaci\u00f3n.<\/li>\n\n\n\n<li><strong>Number Slider (floating point) (Deslizador num\u00e9rico (punto flotante)):<\/strong> se han utilizado un total de 4 deslizadores para las distintas dimensiones de la anotaci\u00f3n.<\/li>\n\n\n\n<li><strong>Number Slider (integer) (Deslizador num\u00e9rico (entero)):<\/strong> especifica la cantidad de decimales.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Output parameters (Par\u00e1metros de salida)<\/strong>: son los componentes que leer\u00e1 VisualARQ una vez creado el estilo. VisualARQ solo reconoce los par\u00e1metros de salida que son componentes finales con sus nodos de salida desconectados. En este ejemplo, encontramos los siguientes par\u00e1metros de salida: \n<ul class=\"wp-block-list\">\n<li><strong>Geometrical outputs (Salidas geom\u00e9tricas)<\/strong>: son los que se leer\u00e1n como partes diferentes del objeto de anotaci\u00f3n.\n<ul class=\"wp-block-list\">\n<li><strong>Text Param (Par\u00e1metro de texto)<\/strong><\/li>\n\n\n\n<li><strong>Geometry Param  (Par\u00e1metro de geometr\u00eda)<\/strong><\/li>\n\n\n\n<li><strong>Hatch Param (Par\u00e1metro de trama)<\/strong><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Output parameters<\/strong>: &nbsp;these are used to retrieve information from the object created. In this example we can find the following output parameter:\n<ul class=\"wp-block-list\">\n<li><strong>Number Param (Par\u00e1metro num\u00e9rico):<\/strong> se utiliza para recuperar la elevaci\u00f3n del objeto de anotaci\u00f3n final.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Es importante asignar nombre a estos componentes en Grasshopper para identificarlos f\u00e1cilmente cuando se crea el nuevo estilo:<\/p>\n<\/blockquote>\n\n<figure class=\"wp-block-image aligncenter size-large size-full wp-image-16468\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"548\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-1-1024x548.png\" alt=\"\" class=\"wp-image-37163\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-1-980x525.png 980w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-1-480x257.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><figcaption class=\"wp-element-caption\">Definici\u00f3n de Grasshopper que genera el objeto de anotaci\u00f3n.<\/figcaption><\/figure>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<h2 class=\"wp-block-heading\" id=\"create\">2. Crear el estilo de anotaci\u00f3n de VisualARQ<\/h2>\n\n<p class=\"wp-block-paragraph\">El estilo de Grasshopper se crear\u00e1 y gestionar\u00e1 desde el di\u00e1logo Estilos de anotaci\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h3 class=\"wp-block-heading\">2.1: Crear el nuevo estilo<\/h3>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1117\" height=\"954\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-2.png\" alt=\"\" class=\"wp-image-37170\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-2.png 1117w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-2-980x837.png 980w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-2-480x410.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1117px, 100vw\" \/><figcaption class=\"wp-element-caption\">Di\u00e1logo Estilos secci\u00f3n<\/figcaption><\/figure>\n\n<ol class=\"wp-block-list\">\n<li>Suponiendo que la definici\u00f3n de Grasshopper (archivo .gh) ya est\u00e1 hecha, abra el di\u00e1logo de estilos de pilar: <code><strong>vaAnotaci\u00f3nEstilos (comando)<\/strong><\/code> .<\/li>\n\n\n\n<li>Haga clic en el bot\u00f3n <strong><em>Nuevo&#8230;<\/em><\/strong> y seleccione la opci\u00f3n <strong>Estilo de anotaci\u00f3n de Grasshopper<\/strong>.<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\">Se abrir\u00e1 el <strong>Asistente de estilos de Grasshopper<\/strong> <strong><\/strong>. Este asistente le guiar\u00e1 en el proceso para definir los par\u00e1metros de estilo de anotaci\u00f3n de Grasshopper. La parte izquierda del asistente muestra una vista previa del estilo de objeto generado una vez se ha completado la informaci\u00f3n requerida.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h3 class=\"wp-block-heading\">2.2 Abrir la definici\u00f3n de Grasshopper<\/h3>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1167\" height=\"885\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-3.png\" alt=\"\" class=\"wp-image-37177\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-3.png 1167w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-3-980x743.png 980w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-3-480x364.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1167px, 100vw\" \/><figcaption class=\"wp-element-caption\">Asistente de estilos de Grasshopper: abra la definici\u00f3n de Grasshopper<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Haga clic en el bot\u00f3n <em>Examinar<\/em> para seleccionar el archivo .gh o elija uno de los archivos recientes de la lista desplegable.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h3 class=\"wp-block-heading\">2.3 Configuraci\u00f3n<\/h3>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1167\" height=\"885\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-4.png\" alt=\"\" class=\"wp-image-37184\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-4.png 1167w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-4-980x743.png 980w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-4-480x364.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1167px, 100vw\" \/><figcaption class=\"wp-element-caption\">Asistente de estilos de Grasshopper: Configuraci\u00f3n<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Defina los valores globales de estilo de anotaci\u00f3n de Grasshopper:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Nombre de estilo<\/strong>: defina el nombre para el estilo.<\/li>\n\n\n\n<li><strong>Unidades de definici\u00f3n<\/strong>: en este caso, se ha preparado en metros.<\/li>\n\n\n\n<li><strong>Insert Plane<\/strong> (<strong>Linked properties<\/strong>): &nbsp;the base point to place the annotation. Any input Plane or Point parameter created in the GH definition will be available here.\n<ul class=\"wp-block-list\">\n<li>Si no se elige ning\u00fan punto o plano (opci\u00f3n \u201c<em>None<\/em>\u201d (Ninguno), se utilizar\u00e1 en su lugar el origen de la definici\u00f3n de GH.  Sin embargo, el valor de elevaci\u00f3n no estar\u00e1 vinculado a la ubicaci\u00f3n de la anotaci\u00f3n.<\/li>\n\n\n\n<li>Si hubiera un punto de entrada en el archivo GH (en lugar de un plano), y se eligiera aqu\u00ed, la anotaci\u00f3n tomar\u00eda la elevaci\u00f3n del plano del punto como referencia, pero su orientaci\u00f3n estar\u00eda restringida al plano de ese punto en la definici\u00f3n de Grasshopper.<\/li>\n\n\n\n<li>Si se elige la entrada de plano, la anotaci\u00f3n se colocar\u00e1 orientada al plano de construcci\u00f3n actual de la vista donde se inserta el objeto. Esta es la opci\u00f3n recomendada en este ejemplo.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\">2.4 Geometr\u00eda<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1167\" height=\"885\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-5.png\" alt=\"\" class=\"wp-image-37191\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-5.png 1167w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-5-980x743.png 980w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-5-480x364.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1167px, 100vw\" \/><figcaption class=\"wp-element-caption\">Asistente de estilos de Grasshopper: Geometr\u00eda<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Especifique qu\u00e9 componentes de geometr\u00eda de salida (Params) se importar\u00e1n a VisualARQ. Los identificadores de estos componentes geom\u00e9tricos se obtienen de los nombres de los componentes geom\u00e9tricos de salida de la definici\u00f3n de Grasshopper y solo pueden modificarse una vez creado el estilo.<\/p>\n\n<p class=\"wp-block-paragraph\">Puede elegir la representaci\u00f3n en la que se utilizar\u00e1 cada componente:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Modelo<\/strong>: representaci\u00f3n del objeto en 3D.<\/li>\n\n\n\n<li><strong>Planta<\/strong>: representaci\u00f3n del objeto en vista en planta. Solo est\u00e1 visible en las vistas superiores cuando est\u00e1 activado el plano de corte del nivel en el que est\u00e1 situado el objeto y se interseca con el objeto.<\/li>\n\n\n\n<li><strong>Vista previa *<\/strong>: representaci\u00f3n del objeto mientras se inserta (o se desplaza posteriormente). De esta forma, puede tener una vista previa del objeto final antes de finalizar el comando. <\/li>\n<\/ul>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>*Nota<\/strong>: es muy recomendable utilizar la representaci\u00f3n de <em>Vista previa<\/em> solo para la geometr\u00eda necesaria que se visualizar\u00e1 al insertar el objeto en el modelo. Cuantos menos componentes se comprueben en la vista previa, m\u00e1s r\u00e1pida ser\u00e1 la inserci\u00f3n o edici\u00f3n de estos objetos en el modelo, especialmente cuando se realizan con definiciones de Grasshopper complejas. Aseg\u00farese de dejar al menos un componente con esta representaci\u00f3n marcada.<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\">En este caso hay tres salidas de geometr\u00eda que queremos mostrar en las tres representaciones diferentes: modelo, planta y vista previa. Esto significa que la representaci\u00f3n en planta se tomar\u00e1 de la secci\u00f3n horizontal del objeto 3D seg\u00fan la altura del plano de corte del nivel.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h3 class=\"wp-block-heading\">2.5 Par\u00e1metros<\/h3>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1167\" height=\"885\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-6.png\" alt=\"\" class=\"wp-image-37198\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-6.png 1167w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-6-980x743.png 980w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-6-480x364.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1167px, 100vw\" \/><figcaption class=\"wp-element-caption\">Asistente de estilos de Grasshopper: Configuraci\u00f3n de par\u00e1metros<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Este paso muestra las opciones disponibles en la lista de par\u00e1metros de entrada y salida definidos en Grasshopper. La opci\u00f3n Filtrar por permite ver los par\u00e1metros que se encuentran dentro de los <strong>grupos con nombre<\/strong> en la definici\u00f3n de Grasshopper. Hay dos tipos de par\u00e1metros:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Par\u00e1metros de entrada<\/strong>: estos par\u00e1metros definen el estilo de la anotaci\u00f3n.<\/li>\n\n\n\n<li><strong>Par\u00e1metros de salida<\/strong>: estos par\u00e1metros recuperan informaci\u00f3n del objeto creado.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Las opciones son diferentes para cada uno de ellos:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Parametros de entrada<\/strong>:\n<ul class=\"wp-block-list\">\n<li><strong>Nombre<\/strong>: es el identificador del par\u00e1metro y puede modificarse en este paso si se desea.<\/li>\n\n\n\n<li><strong>Editable por<\/strong> (puede cambiar este valor para varios par\u00e1metros seleccion\u00e1ndolos mientras mantiene pulsada la tecla Ctrl):\n<ul class=\"wp-block-list\">\n<li><strong>Definici\u00f3n<\/strong>: el par\u00e1metro se ocultar\u00e1 y mantendr\u00e1 el valor de la definici\u00f3n de Grasshopper.<\/li>\n\n\n\n<li><strong>Estilo<\/strong>: el par\u00e1metro solo se puede editar por estilo y los cambios se aplicar\u00e1n a todos los objetos del modelo que tengan ese estilo.<\/li>\n\n\n\n<li><strong>Objeto<\/strong>: permite definir un valor diferente para ese par\u00e1metro para cada pilar del modelo que tenga el mismo estilo. En caso de que no se proporcione ning\u00fan valor \u00abPor objeto\u00bb se utilizar\u00e1 el definido por estilo.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Predeterminado<\/strong> (valor): muestra el valor predeterminado (los especificados en la definici\u00f3n de Grasshopper) de los par\u00e1metros de entrada y permite establecer diferentes valores predeterminados.<\/li>\n\n\n\n<li><strong>Tipo<\/strong>: muestra los diferentes tipos de valores disponibles para cada tipo de par\u00e1metro. En este caso, todos se han ajustado autom\u00e1ticamente a su tipo correspondiente. Casi todos son valores de punto flotante de tipo Longitud, pero tambi\u00e9n hay uno de tipo Entero y otro de tipo Texto.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li><strong>Par\u00e1metros de salida<\/strong>:\n<ul class=\"wp-block-list\">\n<li><strong>Nombre<\/strong>: es el identificador del par\u00e1metro y puede modificarse en este paso si se desea.<\/li>\n\n\n\n<li><strong>Visibilidad:<\/strong> elija la opci\u00f3n \u00ab<em>Objeto<\/em>\u00bb para mostrar este par\u00e1metro en los cuadros de di\u00e1logo de VisualARQ o \u00ab<em>Ninguno<\/em>\u00bb para ocultarlo.<\/li>\n\n\n\n<li><strong>Tipo: <\/strong>muestra el tipo de valor que se ha definido previamente en Grasshopper para este par\u00e1metro.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"edit\">3. Insertar y editar el estilo de anotaci\u00f3n de Grasshopper<\/h2>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h3 class=\"wp-block-heading\">3.1 Editar el estilo de anotaci\u00f3n<\/h3>\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1116\" height=\"954\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-8.png\" alt=\"\" class=\"wp-image-37205\" style=\"width:424px;height:auto\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-8.png 1116w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-8-980x838.png 980w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-8-480x410.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1116px, 100vw\" \/><figcaption class=\"wp-element-caption\">Par\u00e1metros de estilo de anotaci\u00f3n de Grasshopper en el cuadro de di\u00e1logo Estilos de anotaci\u00f3n.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Una vez completado el asistente de estilos de Grasshopper, el nuevo estilo aparecer\u00e1 en la lista de estilos de anotaci\u00f3n con sus subcomponentes correspondientes (S\u00edmbolo, Texto y Trama). Para volver a editar el estilo, haga clic en el nombre del estilo para abrir el men\u00fa contextual y seleccione <em>Editar<\/em>. Esta operaci\u00f3n volver\u00e1 a abrir el asistente de estilos de Grasshopper.<\/p>\n\n<p class=\"wp-block-paragraph\">Los par\u00e1metros de entrada estar\u00e1n disponibles en la pesta\u00f1a \u00abPar\u00e1metros\u00bb y aparecer\u00e1n agrupados como en la definici\u00f3n de Grasshopper. En caso de que el nombre del grupo coincida con una categor\u00eda existente, aparecer\u00e1n en la misma categor\u00eda.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h3 class=\"wp-block-heading\">3.2 Insertar el estilo de Grasshopper<\/h3>\n\n<p class=\"wp-block-paragraph\">Una vez creado el estilo de anotaci\u00f3n, podr\u00e1 insertar una instancia en el documento y cambiar los valores de sus par\u00e1metros desde el icono de anotaci\u00f3n de VisualARQ situado bajo el panel de Propiedades, tal y como funciona con cualquier otro objeto de VisualARQ. Solo se ver\u00e1n los par\u00e1metros de entrada que se hayan configurado como editables \u00ab<em>Por objeto<\/em>\u00bb en el paso 2.5. Tambi\u00e9n se ver\u00e1n los par\u00e1metros de salida en esta parte del panel Propiedades.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1533\" height=\"1009\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-9.png\" alt=\"\" class=\"wp-image-37212\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-9.png 1533w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-9-1280x842.png 1280w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-9-980x645.png 980w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2024\/06\/Annotation-GH-Style-9-480x316.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1533px, 100vw\" \/><figcaption class=\"wp-element-caption\">Par\u00e1metros de anotaci\u00f3n en el panel Propiedades del objeto Anotaci\u00f3n<\/figcaption><\/figure>\n","protected":false},"author":1,"featured_media":0,"parent":17145,"menu_order":0,"template":"","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tutorgroup":[],"class_list":["post-16491","tutorial","type-tutorial","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anotaciones - VisualARQ<\/title>\n<meta name=\"description\" content=\"Aprenda a crear un estilo de anotaci\u00f3n personalizado de VisualARQ desde una definici\u00f3n de Grasshopper. En este tutorial se explican detalladamente todos los pasos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anotaciones - VisualARQ\" \/>\n<meta property=\"og:description\" content=\"Aprenda a crear un estilo de anotaci\u00f3n personalizado de VisualARQ desde una definici\u00f3n de Grasshopper. En este tutorial se explican detalladamente todos los pasos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stg.visualarq.com\/es\/tutorial\/grasshopper-styles\/annotations\/\" \/>\n<meta property=\"og:site_name\" content=\"VisualARQ\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/visualarq\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-23T14:31:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/04\/GH-to-VA-Door-Example.png\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/04\/GH-to-VA-Door-Example.png\" \/>\n<meta name=\"twitter:site\" content=\"@VisualARQ\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/tutorial\\\/grasshopper-styles\\\/annotations\\\/\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/tutorial\\\/grasshopper-styles\\\/annotations\\\/\",\"name\":\"Anotaciones - VisualARQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/tutorial\\\/grasshopper-styles\\\/annotations\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/tutorial\\\/grasshopper-styles\\\/annotations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/GHtoVAAnnotation-1-300x231.png\",\"datePublished\":\"2019-07-26T12:30:32+00:00\",\"dateModified\":\"2024-09-23T14:31:07+00:00\",\"description\":\"Aprenda a crear un estilo de anotaci\u00f3n personalizado de VisualARQ desde una definici\u00f3n de Grasshopper. En este tutorial se explican detalladamente todos los pasos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/tutorial\\\/grasshopper-styles\\\/annotations\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/tutorial\\\/grasshopper-styles\\\/annotations\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/tutorial\\\/grasshopper-styles\\\/annotations\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/GHtoVAAnnotation-1-300x231.png\",\"contentUrl\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/GHtoVAAnnotation-1-300x231.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/tutorial\\\/grasshopper-styles\\\/annotations\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutorials\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/tutorial\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Estilos de Grasshopper\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/tutorial\\\/grasshopper-styles\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Anotaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/\",\"name\":\"VisualARQ\",\"description\":\"Flexible BIM for Rhino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stg.visualarq.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anotaciones - VisualARQ","description":"Aprenda a crear un estilo de anotaci\u00f3n personalizado de VisualARQ desde una definici\u00f3n de Grasshopper. En este tutorial se explican detalladamente todos los pasos.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Anotaciones - VisualARQ","og_description":"Aprenda a crear un estilo de anotaci\u00f3n personalizado de VisualARQ desde una definici\u00f3n de Grasshopper. En este tutorial se explican detalladamente todos los pasos.","og_url":"https:\/\/stg.visualarq.com\/es\/tutorial\/grasshopper-styles\/annotations\/","og_site_name":"VisualARQ","article_publisher":"https:\/\/www.facebook.com\/visualarq","article_modified_time":"2024-09-23T14:31:07+00:00","og_image":[{"width":480,"height":460,"url":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/04\/GH-to-VA-Door-Example.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/04\/GH-to-VA-Door-Example.png","twitter_site":"@VisualARQ","twitter_misc":{"Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stg.visualarq.com\/es\/tutorial\/grasshopper-styles\/annotations\/","url":"https:\/\/stg.visualarq.com\/es\/tutorial\/grasshopper-styles\/annotations\/","name":"Anotaciones - VisualARQ","isPartOf":{"@id":"https:\/\/stg.visualarq.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stg.visualarq.com\/es\/tutorial\/grasshopper-styles\/annotations\/#primaryimage"},"image":{"@id":"https:\/\/stg.visualarq.com\/es\/tutorial\/grasshopper-styles\/annotations\/#primaryimage"},"thumbnailUrl":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/07\/GHtoVAAnnotation-1-300x231.png","datePublished":"2019-07-26T12:30:32+00:00","dateModified":"2024-09-23T14:31:07+00:00","description":"Aprenda a crear un estilo de anotaci\u00f3n personalizado de VisualARQ desde una definici\u00f3n de Grasshopper. En este tutorial se explican detalladamente todos los pasos.","breadcrumb":{"@id":"https:\/\/stg.visualarq.com\/es\/tutorial\/grasshopper-styles\/annotations\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stg.visualarq.com\/es\/tutorial\/grasshopper-styles\/annotations\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stg.visualarq.com\/es\/tutorial\/grasshopper-styles\/annotations\/#primaryimage","url":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/07\/GHtoVAAnnotation-1-300x231.png","contentUrl":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/07\/GHtoVAAnnotation-1-300x231.png"},{"@type":"BreadcrumbList","@id":"https:\/\/stg.visualarq.com\/es\/tutorial\/grasshopper-styles\/annotations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stg.visualarq.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Tutorials","item":"https:\/\/stg.visualarq.com\/es\/tutorial\/"},{"@type":"ListItem","position":3,"name":"Estilos de Grasshopper","item":"https:\/\/stg.visualarq.com\/es\/tutorial\/grasshopper-styles\/"},{"@type":"ListItem","position":4,"name":"Anotaciones"}]},{"@type":"WebSite","@id":"https:\/\/stg.visualarq.com\/es\/#website","url":"https:\/\/stg.visualarq.com\/es\/","name":"VisualARQ","description":"Flexible BIM for Rhino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stg.visualarq.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/tutorial\/16491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/tutorial"}],"about":[{"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/types\/tutorial"}],"author":[{"embeddable":true,"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/tutorial\/16491\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/tutorial\/17145"}],"wp:attachment":[{"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/media?parent=16491"}],"wp:term":[{"taxonomy":"tutorgroup","embeddable":true,"href":"https:\/\/stg.visualarq.com\/es\/wp-json\/wp\/v2\/tutorgroup?post=16491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}