{"id":2305,"date":"2009-06-15T00:00:00","date_gmt":"2009-06-15T00:00:00","guid":{"rendered":"https:\/\/stg.visualarq.com\/support\/tips\/2305\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\/"},"modified":"2021-06-07T14:47:34","modified_gmt":"2021-06-07T14:47:34","slug":"when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them","status":"publish","type":"tip","link":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\/","title":{"rendered":"Lorsque j&rsquo;ouvre un nouveau dessin, les barres d&rsquo;outils de VisualARQ n&rsquo;apparaissent pas \u00e0 l&rsquo;\u00e9cran. Comment puis-je les charger ?"},"content":{"rendered":"Si les barres d&rsquo;outils n&rsquo;apparaissent pas automatiquement apr\u00e8s avoir s\u00e9lectionn\u00e9 un mod\u00e8le de VisualARQ, elles peuvent \u00eatre charg\u00e9es manuellement, de la m\u00eame fa\u00e7on que les celles de Rhino&nbsp;:\n\nTapez <em>BarreOutils<\/em> dans la ligne de commandes et ouvrez le fichier de barres d&rsquo;outils de VisualARQ (<strong>VisualARQ.rui<\/strong>), qui se trouve dans un des dossiers suivants, en fonction de votre version de Rhino&nbsp;:\n<ul>\n \t<li><strong>Dans Rhino 5 (32 et 64 bits) <\/strong>: <code>C:\\Users\\\"Nom d'utilisateur\"\\AppData\\Roaming\\McNeel\\Rhinoceros\\5.0\\UI<\/code><\/li>\n \t<li><strong>Dans Rhino 6 <\/strong> : <code>C:\\Users\\\"Nom d'utilisateur\"\\AppData\\Roaming\\McNeel\\Rhinoceros\\6.0\\UI<\/code><\/li>\n \t<li><strong>Dans Rhino 7 <\/strong> : <code>C:\\Users\\\"Nom d'utilisateur\"\\AppData\\Roaming\\McNeel\\Rhinoceros\\7.0\\UI<\/code><\/li>\n<\/ul>\nLa prochaine fois que vous ouvrez Rhino, les barres d&rsquo;outils de VisualARQ devraient appara\u00eetre \u00e0 l&rsquo;\u00e9cran comme lors de la fermeture de la derni\u00e8re session de Rhino.\n\nSi les barres d&rsquo;outils de VisualARQ n&rsquo;apparaissent toujours pas, il se peut que VisualARQ essaie de charger un ancien fichier de barres d&rsquo;outils. Dans ce cas, vous devrez peut-\u00eatre supprimer manuellement les fichiers de barres d&rsquo;outils <em>\u00ab\u00a0visualarq.rui\u00a0\u00bb<\/em> (des dossiers mentionn\u00e9s ci-dessus), d\u00e9sinstaller VisualARQ et le r\u00e9installer.\n\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14024\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/03\/VAToolbars.png\" alt=\"Les quatre barres d'outils de VisualARQ, de haut en bas, Objets, \u00c9dition, Documentation et Outils\" width=\"353\" height=\"247\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/03\/VAToolbars.png 353w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/03\/VAToolbars-300x210.png 300w\" sizes=\"(max-width: 353px) 100vw, 353px\" \/>\n<blockquote><strong>Plus<\/strong>\n\nConsultez <a href=\"https:\/\/wiki.mcneel.com\/rhino\/toolbarproblems\" target=\"_blank\" rel=\"noopener noreferrer\">cet article de McNeel<\/a>) pour en savoir plus sur le fonctionnement des barres d&rsquo;outils dans Rhino.<\/blockquote>","protected":false},"featured_media":1822,"parent":0,"menu_order":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tipgroup":[98],"class_list":["post-2305","tip","type-tip","status-publish","has-post-thumbnail","hentry","tipgroup-object-lib-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lorsque j&#039;ouvre un nouveau dessin, les barres d&#039;outils de VisualARQ n&#039;apparaissent pas \u00e0 l&#039;\u00e9cran. Comment puis-je les charger ? - VisualARQ<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lorsque j&#039;ouvre un nouveau dessin, les barres d&#039;outils de VisualARQ n&#039;apparaissent pas \u00e0 l&#039;\u00e9cran. Comment puis-je les charger ? - VisualARQ\" \/>\n<meta property=\"og:description\" content=\"Si les barres d&rsquo;outils n&rsquo;apparaissent pas automatiquement apr\u00e8s avoir s\u00e9lectionn\u00e9 un mod\u00e8le de VisualARQ, elles peuvent \u00eatre charg\u00e9es manuellement, de la m\u00eame fa\u00e7on que les celles de Rhino&nbsp;: Tapez BarreOutils dans la ligne de commandes et ouvrez le fichier de barres d&rsquo;outils de VisualARQ (VisualARQ.rui), qui se trouve dans un des dossiers suivants, en fonction [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stg.visualarq.com\/fr\/support\/tip\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\/\" \/>\n<meta property=\"og:site_name\" content=\"VisualARQ\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/visualarq\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-07T14:47:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/VisualARQ-toolbars.png\" \/>\n\t<meta property=\"og:image:width\" content=\"961\" \/>\n\t<meta property=\"og:image:height\" content=\"363\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@VisualARQ\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\\\/\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\\\/\",\"name\":\"Lorsque j'ouvre un nouveau dessin, les barres d'outils de VisualARQ n'apparaissent pas \u00e0 l'\u00e9cran. Comment puis-je les charger ? - VisualARQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/VisualARQ-toolbars.png\",\"datePublished\":\"2009-06-15T00:00:00+00:00\",\"dateModified\":\"2021-06-07T14:47:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/VisualARQ-toolbars.png\",\"contentUrl\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/VisualARQ-toolbars.png\",\"width\":961,\"height\":363},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tips\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lorsque j&#8217;ouvre un nouveau dessin, les barres d&#8217;outils de VisualARQ n&#8217;apparaissent pas \u00e0 l&#8217;\u00e9cran. Comment puis-je les charger ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/\",\"name\":\"VisualARQ\",\"description\":\"Flexible BIM for Rhino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lorsque j'ouvre un nouveau dessin, les barres d'outils de VisualARQ n'apparaissent pas \u00e0 l'\u00e9cran. Comment puis-je les charger ? - VisualARQ","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Lorsque j'ouvre un nouveau dessin, les barres d'outils de VisualARQ n'apparaissent pas \u00e0 l'\u00e9cran. Comment puis-je les charger ? - VisualARQ","og_description":"Si les barres d&rsquo;outils n&rsquo;apparaissent pas automatiquement apr\u00e8s avoir s\u00e9lectionn\u00e9 un mod\u00e8le de VisualARQ, elles peuvent \u00eatre charg\u00e9es manuellement, de la m\u00eame fa\u00e7on que les celles de Rhino&nbsp;: Tapez BarreOutils dans la ligne de commandes et ouvrez le fichier de barres d&rsquo;outils de VisualARQ (VisualARQ.rui), qui se trouve dans un des dossiers suivants, en fonction [&hellip;]","og_url":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\/","og_site_name":"VisualARQ","article_publisher":"https:\/\/www.facebook.com\/visualarq","article_modified_time":"2021-06-07T14:47:34+00:00","og_image":[{"width":961,"height":363,"url":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/VisualARQ-toolbars.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@VisualARQ","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\/","url":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\/","name":"Lorsque j'ouvre un nouveau dessin, les barres d'outils de VisualARQ n'apparaissent pas \u00e0 l'\u00e9cran. Comment puis-je les charger ? - VisualARQ","isPartOf":{"@id":"https:\/\/stg.visualarq.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\/#primaryimage"},"image":{"@id":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\/#primaryimage"},"thumbnailUrl":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/VisualARQ-toolbars.png","datePublished":"2009-06-15T00:00:00+00:00","dateModified":"2021-06-07T14:47:34+00:00","breadcrumb":{"@id":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stg.visualarq.com\/fr\/support\/tip\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\/#primaryimage","url":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/VisualARQ-toolbars.png","contentUrl":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/VisualARQ-toolbars.png","width":961,"height":363},{"@type":"BreadcrumbList","@id":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/when-i-open-a-new-drawing-visualarq-toolbars-dont-appear-on-the-screen-how-can-i-load-them\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stg.visualarq.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Tips","item":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/"},{"@type":"ListItem","position":3,"name":"Lorsque j&#8217;ouvre un nouveau dessin, les barres d&#8217;outils de VisualARQ n&#8217;apparaissent pas \u00e0 l&#8217;\u00e9cran. Comment puis-je les charger ?"}]},{"@type":"WebSite","@id":"https:\/\/stg.visualarq.com\/fr\/#website","url":"https:\/\/stg.visualarq.com\/fr\/","name":"VisualARQ","description":"Flexible BIM for Rhino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stg.visualarq.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/stg.visualarq.com\/fr\/wp-json\/wp\/v2\/tip\/2305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.visualarq.com\/fr\/wp-json\/wp\/v2\/tip"}],"about":[{"href":"https:\/\/stg.visualarq.com\/fr\/wp-json\/wp\/v2\/types\/tip"}],"version-history":[{"count":0,"href":"https:\/\/stg.visualarq.com\/fr\/wp-json\/wp\/v2\/tip\/2305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.visualarq.com\/fr\/wp-json\/wp\/v2\/media\/1822"}],"wp:attachment":[{"href":"https:\/\/stg.visualarq.com\/fr\/wp-json\/wp\/v2\/media?parent=2305"}],"wp:term":[{"taxonomy":"tipgroup","embeddable":true,"href":"https:\/\/stg.visualarq.com\/fr\/wp-json\/wp\/v2\/tipgroup?post=2305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}