{"id":2325,"date":"2009-03-16T00:00:00","date_gmt":"2009-03-16T00:00:00","guid":{"rendered":"https:\/\/stg.visualarq.com\/support\/tips\/2325\/what-are-the-steps-to-create-a-roof\/"},"modified":"2024-09-27T07:24:14","modified_gmt":"2024-09-27T07:24:14","slug":"what-are-the-steps-to-create-a-roof","status":"publish","type":"tip","link":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/what-are-the-steps-to-create-a-roof\/","title":{"rendered":"Quelles sont les \u00e9tapes pour cr\u00e9er un toit ?"},"content":{"rendered":"<p>Il existe trois types de toit pouvant \u00eatre cr\u00e9\u00e9s dans VisualARQ avec la commande <em>vaToit<\/em> : <strong>Croupe<\/strong>, <strong>Pignon<\/strong> et <strong>Appenti<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Toit en croupe :<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"Hip Roof\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/Hip-Roof.png\" alt=\"\" width=\"400\" height=\"270\" align=\"right\" style=\"padding-left:10px;\" \/><\/p>\n<ol>\n<li>Lancez la commande vaMur. S\u00e9lectionnez un type de toit en croupe dans la bo\u00eete de dialogue d&rsquo;insertion.<\/em><\/li>\n<li>S\u00e9lectionnez le type <strong>Croupe<\/strong> dans la <em>ligne de commandes<\/em>.<\/li>\n<li>Indiquez l&rsquo;<strong>angle de pente<\/strong> du toit. <\/li>\n<li>Indiquez l&rsquo;<strong>\u00e9paisseur<\/strong> du toit. <\/li>\n<\/ol>\n<p><br clear=\"all\" \/><\/p>\n<p><strong>Toit \u00e0 pignon<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"Gable Roof\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/Gable-Roof.png\" alt=\"\" width=\"400\" height=\"270\" align=\"right\" style=\"padding-left:10px;\" \/><\/p>\n<ol>\n<li>Dessinez une <strong>Courbe<\/strong>  qui sera utilis\u00e9e comme limite du toit. Cette courbe doit \u00eatre <em>plane<\/em> et <em>ferm\u00e9e.<\/em><\/li>\n<li>S\u00e9lectionnez le type <strong>Pignon<\/strong> dans la <em>ligne de commandes<\/em>.<\/li>\n<li>Indiquez l&rsquo;<strong>angle de pente<\/strong> du toit.<\/li>\n<li>Indiquez l&rsquo;<strong>\u00e9paisseur<\/strong> du toit.<\/li>\n<li>D\u00e9finissez la <strong>direction de l&rsquo;axe<\/strong> repr\u00e9sentant l&rsquo;ar\u00eate du pignon<strong>.<\/strong><\/li>\n<\/ol>\n<p><br clear=\"all\" \/><\/p>\n<p><strong>Toit en appenti :<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"Shed Roof\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/Shed-Roof.png\" alt=\"\" width=\"400\" height=\"270\" align=\"right\" style=\"padding-left:10px;\" \/><\/p>\n<ol>\n<li>Dessinez une <strong>Courbe<\/strong>  qui sera utilis\u00e9e comme limite du toit. Cette courbe doit \u00eatre <em>plane<\/em> et <em>ferm\u00e9e<\/em>.<\/li>\n<li>S\u00e9lectionnez le type <strong>Appenti<\/strong> dans la ligne de commandes. <\/li>\n<li>Tapez une valeur pour d\u00e9finir l&rsquo;<strong>angle de pente<\/strong> du toit. <\/li>\n<li>Indiquez l&rsquo;<strong>\u00e9paisseur<\/strong> du toit.<\/li>\n<li>S\u00e9lectionnez les <strong>points de d\u00e9part et final de l&rsquo;axe du toit<\/strong>. Ces points d\u00e9finiront la hauteur du plan inf\u00e9rieur du toit en appenti.<\/li>\n<\/ol>\n<p><br clear=\"all\" \/><\/p>\n<p>Vous pouvez modifier le contour du toit en d\u00e9pla\u00e7ant les <strong>points de contr\u00f4le du toit<\/strong> et en ajoutant ou en supprimant des contours avec les commandes <strong>vaToitAjouter<\/strong> et <strong>vaToitSoustraire<\/strong>.<\/p>\n<p>Vous pouvez \u00e9galement modifier l&rsquo;angle de pente avec la commande <strong>vaToitChangerAnglePente<\/strong> ou dans la section VisualARQ des propri\u00e9t\u00e9s de Rhino.<\/p>\n<p>D&rsquo;autres options sont disponibles pour la modification des toits de VisualARQ dans les propri\u00e9t\u00e9s :<\/p>\n<ul>\n<li>Changer le <strong>type de toit <\/strong>: appentis, \u00e0 pignon et en croupe. <\/li>\n<li>Changer le <strong>bord<\/strong> du toit : plat, vertical et carr\u00e9. <\/li>\n<li>Changer l&rsquo;<strong>orientation de l&rsquo;axe<\/strong> (uniquement pour les toits \u00e0 pignon). <\/li>\n<li>Changer la <strong>hauteur du bord sup\u00e9rieur<\/strong> (uniquement pour les toits en croupe). <\/li>\n<\/ul>\n<p>&nbsp;<\/p>","protected":false},"featured_media":1757,"parent":0,"menu_order":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tipgroup":[134],"class_list":["post-2325","tip","type-tip","status-publish","has-post-thumbnail","hentry","tipgroup-roofs-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quelles sont les \u00e9tapes pour cr\u00e9er un toit ? - VisualARQ<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quelles sont les \u00e9tapes pour cr\u00e9er un toit ? - VisualARQ\" \/>\n<meta property=\"og:description\" content=\"Il existe trois types de toit pouvant \u00eatre cr\u00e9\u00e9s dans VisualARQ avec la commande vaToit : Croupe, Pignon et Appenti. &nbsp; Toit en croupe : Lancez la commande vaMur. S\u00e9lectionnez un type de toit en croupe dans la bo\u00eete de dialogue d&rsquo;insertion. S\u00e9lectionnez le type Croupe dans la ligne de commandes. Indiquez l&rsquo;angle de pente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stg.visualarq.com\/fr\/support\/tip\/what-are-the-steps-to-create-a-roof\/\" \/>\n<meta property=\"og:site_name\" content=\"VisualARQ\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/visualarq\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-27T07:24:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/Shed-Roof.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@VisualARQ\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/what-are-the-steps-to-create-a-roof\\\/\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/what-are-the-steps-to-create-a-roof\\\/\",\"name\":\"Quelles sont les \u00e9tapes pour cr\u00e9er un toit ? - VisualARQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/what-are-the-steps-to-create-a-roof\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/what-are-the-steps-to-create-a-roof\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Shed-Roof.png\",\"datePublished\":\"2009-03-16T00:00:00+00:00\",\"dateModified\":\"2024-09-27T07:24:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/what-are-the-steps-to-create-a-roof\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/what-are-the-steps-to-create-a-roof\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/what-are-the-steps-to-create-a-roof\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Shed-Roof.png\",\"contentUrl\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Shed-Roof.png\",\"width\":400,\"height\":270},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/what-are-the-steps-to-create-a-roof\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tips\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/support\\\/tip\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quelles sont les \u00e9tapes pour cr\u00e9er un toit ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/\",\"name\":\"VisualARQ\",\"description\":\"Flexible BIM for Rhino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stg.visualarq.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quelles sont les \u00e9tapes pour cr\u00e9er un toit ? - VisualARQ","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Quelles sont les \u00e9tapes pour cr\u00e9er un toit ? - VisualARQ","og_description":"Il existe trois types de toit pouvant \u00eatre cr\u00e9\u00e9s dans VisualARQ avec la commande vaToit : Croupe, Pignon et Appenti. &nbsp; Toit en croupe : Lancez la commande vaMur. S\u00e9lectionnez un type de toit en croupe dans la bo\u00eete de dialogue d&rsquo;insertion. S\u00e9lectionnez le type Croupe dans la ligne de commandes. Indiquez l&rsquo;angle de pente [&hellip;]","og_url":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/what-are-the-steps-to-create-a-roof\/","og_site_name":"VisualARQ","article_publisher":"https:\/\/www.facebook.com\/visualarq","article_modified_time":"2024-09-27T07:24:14+00:00","og_image":[{"width":400,"height":270,"url":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/Shed-Roof.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@VisualARQ","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/what-are-the-steps-to-create-a-roof\/","url":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/what-are-the-steps-to-create-a-roof\/","name":"Quelles sont les \u00e9tapes pour cr\u00e9er un toit ? - VisualARQ","isPartOf":{"@id":"https:\/\/stg.visualarq.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/what-are-the-steps-to-create-a-roof\/#primaryimage"},"image":{"@id":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/what-are-the-steps-to-create-a-roof\/#primaryimage"},"thumbnailUrl":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/Shed-Roof.png","datePublished":"2009-03-16T00:00:00+00:00","dateModified":"2024-09-27T07:24:14+00:00","breadcrumb":{"@id":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/what-are-the-steps-to-create-a-roof\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stg.visualarq.com\/fr\/support\/tip\/what-are-the-steps-to-create-a-roof\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/what-are-the-steps-to-create-a-roof\/#primaryimage","url":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/Shed-Roof.png","contentUrl":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2018\/12\/Shed-Roof.png","width":400,"height":270},{"@type":"BreadcrumbList","@id":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/what-are-the-steps-to-create-a-roof\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stg.visualarq.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Tips","item":"https:\/\/stg.visualarq.com\/fr\/support\/tip\/"},{"@type":"ListItem","position":3,"name":"Quelles sont les \u00e9tapes pour cr\u00e9er un toit ?"}]},{"@type":"WebSite","@id":"https:\/\/stg.visualarq.com\/fr\/#website","url":"https:\/\/stg.visualarq.com\/fr\/","name":"VisualARQ","description":"Flexible BIM for Rhino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stg.visualarq.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/stg.visualarq.com\/fr\/wp-json\/wp\/v2\/tip\/2325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.visualarq.com\/fr\/wp-json\/wp\/v2\/tip"}],"about":[{"href":"https:\/\/stg.visualarq.com\/fr\/wp-json\/wp\/v2\/types\/tip"}],"version-history":[{"count":0,"href":"https:\/\/stg.visualarq.com\/fr\/wp-json\/wp\/v2\/tip\/2325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.visualarq.com\/fr\/wp-json\/wp\/v2\/media\/1757"}],"wp:attachment":[{"href":"https:\/\/stg.visualarq.com\/fr\/wp-json\/wp\/v2\/media?parent=2325"}],"wp:term":[{"taxonomy":"tipgroup","embeddable":true,"href":"https:\/\/stg.visualarq.com\/fr\/wp-json\/wp\/v2\/tipgroup?post=2325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}