{"id":17760,"date":"2019-12-18T12:02:10","date_gmt":"2019-12-18T12:02:10","guid":{"rendered":"https:\/\/stg.visualarq.com\/2019\/12\/18\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/"},"modified":"2019-12-18T12:02:10","modified_gmt":"2019-12-18T12:02:10","slug":"workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona","status":"publish","type":"post","link":"https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/","title":{"rendered":"Workshop: Rhino per l&#8217;architettura utilizzando VisualARQ presso McNeel Europe (Barcellona)."},"content":{"rendered":"<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/12\/VisualARQ-Workshop-2020-Banner.png\" alt=\"\" width=\"900\" height=\"393\" class=\"aligncenter size-full wp-image-17675\" srcset=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/12\/VisualARQ-Workshop-2020-Banner.png 900w, https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/12\/VisualARQ-Workshop-2020-Banner-480x210.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/>\n\n<b>Workshop su Rhino per l&#8217;architettura utilizzando VisualARQ<\/b>\n<ul>\n<li><b>Date<\/b>: 3-4 febbraio 2020<\/li>\n<li><b>Orario<\/b>: 10:00-18:00<\/li>\n<li><b>Dove:<\/b>McNeel Europe, Roger de Flor 32-34 bajos, 08018 Barcellona<\/li>\n<\/ul>\n\n<p>McNeel Europe d\u00e0 il benvenuto a Francesc Salla, Product Manager di VisualARQ (AsuniCAD), per impartire un workshop di 2 giorni su BIM orientato a Rhino per architetti, ingegneri e designer presso la sede di Barcellona. <\/p>\n\n<p>VisualARQ aggiunge funzionalit\u00e0 di BIM flessibile a Rhino e Grasshopper. L&#8217;obiettivo del workshop \u00e8 imparare a utilizzare Rhino, VisualARQ e Grasshopper come soluzioni di BIM flessibile per sviluppare e portare avanti progetti di architettura da un modello 3D a documentazione 2D. Il workshop aiuter\u00e0 i partecipanti a migliorare le abilit\u00e0 di progettazione architettonica e il flusso di lavoro progettuale parametrico in Rhino e Grasshopper.<\/p>\n\n<b>Giorno 1: creazione di modelli BIM in Rhino e documentazione 2D:<\/b>\n\n<ul>\n<li>Configurazione del progetto, tipi di oggetti, livelli e modelli.<\/li>\n<li>Gestire il modello con livelli e sezioni.<\/li>\n<li>Lavorare con gli oggetti architettonici parametrici 3D durante la creazione di un nuovo progetto.<\/li>\n<li>Creare nuovi oggetti parametrici personalizzati, anche con Grasshopper.<\/li>\n<li>Aggiungere dati personalizzati alla geometria nel modello.<\/li>\n<li>Creare elenchi per tabelle di computo.<\/li>\n<li>Quote, aree, annotazioni e altri strumenti di disegno tecnico 2D.<\/li>\n<li>Stampa dell&#8217;output vettoriale e configurazione del layout di pagina.<\/li>\n<\/ul>\n\n<b>Giorno 2: BIM di Grasshopper, interoperabilit\u00e0 e dati BIM:<\/b>\n<ul>\n<li>Automatizzare il flusso di lavoro con VisualARQ Grasshopper Components.<\/li>\n<li>Importazione ed esportazione di modelli 3D mediante IFC.<\/li>\n<li>Aggiunta di informazioni IFC personalizzate alla geometria, anche da Grasshopper.<\/li>\n<li>Collaborazione tra team con riferimenti esterni.<\/li>\n<\/ul>\n\n<b>Requisiti:<\/b>\n<ul>\n<li>Nozioni di base di Rhino.<\/li>\n<li>VisualARQ 2, <a href=\"https:\/\/stg.visualarq.com\/it\/download\/\">link di download<\/a>. Se la versione di valutazione scade durante i giorni del corso, \u00e8 possibile richiedere una licenza temporanea inviando un&#8217;e-mail a <a href=\"mailto:visualarq@asuni.com\">visualarq@asuni.com<\/a>.<\/li>\n<li>Rhino 6 per Windows<\/li>\n<\/ul>\n\n<b>Altri dettagli<\/b>:\n<ul>\n\n<li><b>Prezzo del corso<\/b>: 530\u20ac (+ IVA). Gli studenti full-time, gli insegnanti di Universit\u00e0 (prova dello status richiesta) e i partecipanti da remoto otterranno uno sconto del 50%. Il corso viene confermato solo dopo l&#8217;avvenuto pagamento. I partecipanti al workshop potranno ottenere uno sconto sull&#8217;acquisto di una licenza di VisualARQ 2.<\/li>\n<li><b>Numero massimo di partecipanti<\/b>: 10 + 5 da remoto. Se non viene raggiunto il numero minimo di partecipanti, il corso verr\u00e0 annullato con 15 giorni di anticipo.<\/li>\n<li><b>Lingua<\/b>: inglese.<\/li>\n<\/ul>\n\n\nI posti riservati a studenti e insegnanti sono limitati. Iscriviti contattando McNeel Europe <a href=\"mailto:tech.eu@mcneel.com\">qui<\/a>!","protected":false},"excerpt":{"rendered":"<p>Workshop su Rhino per l&#8217;architettura utilizzando VisualARQ Date: 3-4 febbraio 2020 Orario: 10:00-18:00 Dove:McNeel Europe, Roger de Flor 32-34 bajos, 08018 Barcellona McNeel Europe d\u00e0 il benvenuto a Francesc Salla, Product Manager di VisualARQ (AsuniCAD), per impartire un workshop di 2 giorni su BIM orientato a Rhino per architetti, ingegneri e designer presso la sede [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":17672,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1737],"tags":[],"class_list":["post-17760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Workshop: Rhino per l&#039;architettura utilizzando VisualARQ presso McNeel Europe (Barcellona). - VisualARQ<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Workshop: Rhino per l&#039;architettura utilizzando VisualARQ presso McNeel Europe (Barcellona). - VisualARQ\" \/>\n<meta property=\"og:description\" content=\"Workshop su Rhino per l&#8217;architettura utilizzando VisualARQ Date: 3-4 febbraio 2020 Orario: 10:00-18:00 Dove:McNeel Europe, Roger de Flor 32-34 bajos, 08018 Barcellona McNeel Europe d\u00e0 il benvenuto a Francesc Salla, Product Manager di VisualARQ (AsuniCAD), per impartire un workshop di 2 giorni su BIM orientato a Rhino per architetti, ingegneri e designer presso la sede [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/\" \/>\n<meta property=\"og:site_name\" content=\"VisualARQ\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/visualarq\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-18T12:02:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/12\/VisualARQ-Workshop-2020-Banner-FI.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Francesc Salla\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@VisualARQ\" \/>\n<meta name=\"twitter:site\" content=\"@VisualARQ\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesc Salla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\\\/\"},\"author\":{\"name\":\"Francesc Salla\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/#\\\/schema\\\/person\\\/f61c67cb6ff7f707ad48dc1bd00d7371\"},\"headline\":\"Workshop: Rhino per l&#8217;architettura utilizzando VisualARQ presso McNeel Europe (Barcellona).\",\"datePublished\":\"2019-12-18T12:02:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\\\/\"},\"wordCount\":378,\"image\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/VisualARQ-Workshop-2020-Banner-FI.png\",\"articleSection\":[\"Corsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\\\/\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\\\/\",\"name\":\"Workshop: Rhino per l'architettura utilizzando VisualARQ presso McNeel Europe (Barcellona). - VisualARQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/VisualARQ-Workshop-2020-Banner-FI.png\",\"datePublished\":\"2019-12-18T12:02:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/#\\\/schema\\\/person\\\/f61c67cb6ff7f707ad48dc1bd00d7371\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/VisualARQ-Workshop-2020-Banner-FI.png\",\"contentUrl\":\"https:\\\/\\\/stg.visualarq.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/VisualARQ-Workshop-2020-Banner-FI.png\",\"width\":400,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Workshop: Rhino per l&#8217;architettura utilizzando VisualARQ presso McNeel Europe (Barcellona).\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/\",\"name\":\"VisualARQ\",\"description\":\"Flexible BIM for Rhino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/#\\\/schema\\\/person\\\/f61c67cb6ff7f707ad48dc1bd00d7371\",\"name\":\"Francesc Salla\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1b28734ac3202a82f88519e56a2c30dc3797cf97a12b6ab9483115421139fb8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1b28734ac3202a82f88519e56a2c30dc3797cf97a12b6ab9483115421139fb8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1b28734ac3202a82f88519e56a2c30dc3797cf97a12b6ab9483115421139fb8?s=96&d=mm&r=g\",\"caption\":\"Francesc Salla\"},\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/author\\\/fsalla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Workshop: Rhino per l'architettura utilizzando VisualARQ presso McNeel Europe (Barcellona). - VisualARQ","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Workshop: Rhino per l'architettura utilizzando VisualARQ presso McNeel Europe (Barcellona). - VisualARQ","og_description":"Workshop su Rhino per l&#8217;architettura utilizzando VisualARQ Date: 3-4 febbraio 2020 Orario: 10:00-18:00 Dove:McNeel Europe, Roger de Flor 32-34 bajos, 08018 Barcellona McNeel Europe d\u00e0 il benvenuto a Francesc Salla, Product Manager di VisualARQ (AsuniCAD), per impartire un workshop di 2 giorni su BIM orientato a Rhino per architetti, ingegneri e designer presso la sede [&hellip;]","og_url":"https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/","og_site_name":"VisualARQ","article_publisher":"https:\/\/www.facebook.com\/visualarq","article_published_time":"2019-12-18T12:02:10+00:00","og_image":[{"width":400,"height":250,"url":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/12\/VisualARQ-Workshop-2020-Banner-FI.png","type":"image\/png"}],"author":"Francesc Salla","twitter_card":"summary_large_image","twitter_creator":"@VisualARQ","twitter_site":"@VisualARQ","twitter_misc":{"Scritto da":"Francesc Salla","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/#article","isPartOf":{"@id":"https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/"},"author":{"name":"Francesc Salla","@id":"https:\/\/stg.visualarq.com\/it\/#\/schema\/person\/f61c67cb6ff7f707ad48dc1bd00d7371"},"headline":"Workshop: Rhino per l&#8217;architettura utilizzando VisualARQ presso McNeel Europe (Barcellona).","datePublished":"2019-12-18T12:02:10+00:00","mainEntityOfPage":{"@id":"https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/"},"wordCount":378,"image":{"@id":"https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/#primaryimage"},"thumbnailUrl":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/12\/VisualARQ-Workshop-2020-Banner-FI.png","articleSection":["Corsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/","url":"https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/","name":"Workshop: Rhino per l'architettura utilizzando VisualARQ presso McNeel Europe (Barcellona). - VisualARQ","isPartOf":{"@id":"https:\/\/stg.visualarq.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/#primaryimage"},"image":{"@id":"https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/#primaryimage"},"thumbnailUrl":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/12\/VisualARQ-Workshop-2020-Banner-FI.png","datePublished":"2019-12-18T12:02:10+00:00","author":{"@id":"https:\/\/stg.visualarq.com\/it\/#\/schema\/person\/f61c67cb6ff7f707ad48dc1bd00d7371"},"breadcrumb":{"@id":"https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/#primaryimage","url":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/12\/VisualARQ-Workshop-2020-Banner-FI.png","contentUrl":"https:\/\/stg.visualarq.com\/wp-content\/uploads\/2019\/12\/VisualARQ-Workshop-2020-Banner-FI.png","width":400,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/stg.visualarq.com\/it\/workshop-rhino-per-larchitettura-utilizzando-visualarq-presso-mcneel-europe-barcellona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stg.visualarq.com\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Workshop: Rhino per l&#8217;architettura utilizzando VisualARQ presso McNeel Europe (Barcellona)."}]},{"@type":"WebSite","@id":"https:\/\/stg.visualarq.com\/it\/#website","url":"https:\/\/stg.visualarq.com\/it\/","name":"VisualARQ","description":"Flexible BIM for Rhino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stg.visualarq.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/stg.visualarq.com\/it\/#\/schema\/person\/f61c67cb6ff7f707ad48dc1bd00d7371","name":"Francesc Salla","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d1b28734ac3202a82f88519e56a2c30dc3797cf97a12b6ab9483115421139fb8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d1b28734ac3202a82f88519e56a2c30dc3797cf97a12b6ab9483115421139fb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d1b28734ac3202a82f88519e56a2c30dc3797cf97a12b6ab9483115421139fb8?s=96&d=mm&r=g","caption":"Francesc Salla"},"url":"https:\/\/stg.visualarq.com\/it\/author\/fsalla\/"}]}},"_links":{"self":[{"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/posts\/17760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/comments?post=17760"}],"version-history":[{"count":0,"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/posts\/17760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/media\/17672"}],"wp:attachment":[{"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/media?parent=17760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/categories?post=17760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/tags?post=17760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}