{"id":2513,"date":"2009-06-15T00:00:00","date_gmt":"2009-06-15T00:00:00","guid":{"rendered":"https:\/\/stg.visualarq.com\/support\/tips\/2513\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/"},"modified":"2021-06-16T10:16:21","modified_gmt":"2021-06-16T10:16:21","slug":"when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear","status":"publish","type":"tip","link":"https:\/\/stg.visualarq.com\/it\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/","title":{"rendered":"Quando apro un nuovo disegno, i template di VisualARQ non appaiono nella finestra di dialogo dei modelli template&#8230; Come posso farli apparire?"},"content":{"rendered":"Se durante l&#8217;apertura di un nuovo file, i template di VisualARQ non appaiono nella finestra di dialogo dei modelli disponibili, le ragioni possono essere due:\n\n<hr class=\"separator\">\n<h2>I file non si trovano nella stessa cartella dei modelli template di Rhino<\/h2>\nPer renderli visibili, copiare i file dei modelli template di VisualARQ nella stessa cartella in cui si trovano i modelli template di Rhino.\n\nNelle opzioni di Rhino, in Strumenti > Opzioni > Propriet\u00e0 del documento > Posizione, \u00e8 possibile controllare in quale cartella vengono salvati i modelli template.\n\nI file dei modelli template di VisualARQ e le directory in cui essi vengono creati quando VisualARQ viene installato sono i seguenti:\n<ul>\n \t<li style=\"list-style-type: none;\">\n<ul>\n \t<li><strong>VisualARQ &#8211; Metri.3dm<\/strong><\/li>\n \t<li><strong>VisualARQ &#8211; Millimetri.3dm<\/strong><\/li>\n \t<li><strong>VisualARQ &#8211; Piedi.3dm<\/strong><\/li>\n \t<li><strong>VisualARQ &#8211; Pollici.3dm<\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n \t<li><b>In Rhino 7:<\/b><\/li>\n<\/ul>\n<code>C:\\Users\\<em>\"UserName\"<\/em>\\AppData\\Roaming\\McNeel\\Rhinoceros\\7.0\\Localization\\en-US\\Template Files<\/code>\n<ul>\n \t<li><b>In Rhino 6:<\/b><\/li>\n<\/ul>\n<code>C:\\Users\\<em>\"UserName\"<\/em>\\AppData\\Roaming\\McNeel\\Rhinoceros\\6.0\\Localization\\en-US\\Template Files<\/code>\n<ul>\n \t<li><b>In Rhino 5, 32 e 64 bit:<\/b><\/li>\n<\/ul>\n<code>C:\\Users\\<em>\"UserName\"<\/em>\\AppData\\Roaming\\McNeel\\Rhinoceros\\5.0\\Localization\\en-US\\Template Files<\/code>\n\nQuesta \u00e8 la cartella dei modelli template in inglese. I modelli template nelle altre lingue sono contenuti nelle corrispondenti cartelle localizzate: &#8220;it-IT&#8221; anzich\u00e9 &#8220;en-US&#8221; per l&#8217;italiano).\n<hr class=\"separator\">\n<h2>VisualARQ \u00e8 stato installato da un&#8217;altra sessione utente di Windows<\/h2>\nIn questo caso, occorrer\u00e0 accedere alla macchina con lo stesso account utente con cui si \u00e8 installato VisualARQ, copiare i file modello template (cos\u00ec come il file delle barre degli strumenti) su una cartella o posizione esterna (la cartella di un server virtuale o un pendrive USB), accedere alla macchina con l&#8217;altro account utente e copiare i file modello template di VisualARQ sulla stessa cartella in cui si trovano i modelli template di Rhino.","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tipgroup":[100],"class_list":["post-2513","tip","type-tip","status-publish","hentry","tipgroup-object-lib-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quando apro un nuovo disegno, i template di VisualARQ non appaiono nella finestra di dialogo dei modelli template... Come posso farli apparire? - VisualARQ<\/title>\n<meta name=\"description\" content=\"Se mancano i modelli template, dovresti avere una copia dei file template di VisualARQ nella cartella dove si trovano i template di Rhino.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quando apro un nuovo disegno, i template di VisualARQ non appaiono nella finestra di dialogo dei modelli template... Come posso farli apparire? - VisualARQ\" \/>\n<meta property=\"og:description\" content=\"Se mancano i modelli template, dovresti avere una copia dei file template di VisualARQ nella cartella dove si trovano i template di Rhino.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stg.visualarq.com\/it\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/\" \/>\n<meta property=\"og:site_name\" content=\"VisualARQ\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/visualarq\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-16T10:16:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@VisualARQ\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/support\\\/tip\\\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\\\/\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/support\\\/tip\\\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\\\/\",\"name\":\"Quando apro un nuovo disegno, i template di VisualARQ non appaiono nella finestra di dialogo dei modelli template... Come posso farli apparire? - VisualARQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/#website\"},\"datePublished\":\"2009-06-15T00:00:00+00:00\",\"dateModified\":\"2021-06-16T10:16:21+00:00\",\"description\":\"Se mancano i modelli template, dovresti avere una copia dei file template di VisualARQ nella cartella dove si trovano i template di Rhino.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/support\\\/tip\\\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/support\\\/tip\\\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/support\\\/tip\\\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tips\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/support\\\/tip\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quando apro un nuovo disegno, i template di VisualARQ non appaiono nella finestra di dialogo dei modelli template&#8230; Come posso farli apparire?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/\",\"name\":\"VisualARQ\",\"description\":\"Flexible BIM for Rhino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quando apro un nuovo disegno, i template di VisualARQ non appaiono nella finestra di dialogo dei modelli template... Come posso farli apparire? - VisualARQ","description":"Se mancano i modelli template, dovresti avere una copia dei file template di VisualARQ nella cartella dove si trovano i template di Rhino.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Quando apro un nuovo disegno, i template di VisualARQ non appaiono nella finestra di dialogo dei modelli template... Come posso farli apparire? - VisualARQ","og_description":"Se mancano i modelli template, dovresti avere una copia dei file template di VisualARQ nella cartella dove si trovano i template di Rhino.","og_url":"https:\/\/stg.visualarq.com\/it\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/","og_site_name":"VisualARQ","article_publisher":"https:\/\/www.facebook.com\/visualarq","article_modified_time":"2021-06-16T10:16:21+00:00","twitter_card":"summary_large_image","twitter_site":"@VisualARQ","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stg.visualarq.com\/it\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/","url":"https:\/\/stg.visualarq.com\/it\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/","name":"Quando apro un nuovo disegno, i template di VisualARQ non appaiono nella finestra di dialogo dei modelli template... Come posso farli apparire? - VisualARQ","isPartOf":{"@id":"https:\/\/stg.visualarq.com\/it\/#website"},"datePublished":"2009-06-15T00:00:00+00:00","dateModified":"2021-06-16T10:16:21+00:00","description":"Se mancano i modelli template, dovresti avere una copia dei file template di VisualARQ nella cartella dove si trovano i template di Rhino.","breadcrumb":{"@id":"https:\/\/stg.visualarq.com\/it\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stg.visualarq.com\/it\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stg.visualarq.com\/it\/support\/tip\/when-i-open-a-new-drawing-the-visualarq-templates-are-not-displayed-in-the-templates-dialog-box-how-can-i-make-them-appear\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stg.visualarq.com\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Tips","item":"https:\/\/stg.visualarq.com\/it\/support\/tip\/"},{"@type":"ListItem","position":3,"name":"Quando apro un nuovo disegno, i template di VisualARQ non appaiono nella finestra di dialogo dei modelli template&#8230; Come posso farli apparire?"}]},{"@type":"WebSite","@id":"https:\/\/stg.visualarq.com\/it\/#website","url":"https:\/\/stg.visualarq.com\/it\/","name":"VisualARQ","description":"Flexible BIM for Rhino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stg.visualarq.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/tip\/2513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/tip"}],"about":[{"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/types\/tip"}],"version-history":[{"count":0,"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/tip\/2513\/revisions"}],"wp:attachment":[{"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/media?parent=2513"}],"wp:term":[{"taxonomy":"tipgroup","embeddable":true,"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/tipgroup?post=2513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}