{"id":25652,"date":"2022-02-08T14:52:09","date_gmt":"2022-02-08T14:52:09","guid":{"rendered":"https:\/\/stg.visualarq.com\/support\/tip\/suggerimenti-per-ottimizzare-il-flusso-di-lavoro-con-file-di-grandi-dimensioni-in-rhino\/"},"modified":"2022-05-17T11:14:36","modified_gmt":"2022-05-17T11:14:36","slug":"tips-to-streamline-the-workflow-with-large-files-in-rhino","status":"publish","type":"tip","link":"https:\/\/stg.visualarq.com\/it\/support\/tip\/tips-to-streamline-the-workflow-with-large-files-in-rhino\/","title":{"rendered":"Suggerimenti per ottimizzare il flusso di lavoro con file di grandi dimensioni in Rhino"},"content":{"rendered":"<p>Per gestire file di grandi dimensioni in Rhino, puoi seguire alcuni dei seguenti suggerimenti che ti aiuteranno a ottimizzare il flusso di lavoro in Rhino e VisualARQ:<\/p>\n\n<p><strong>Mostrare livelli e deselezionare il piano di taglio<\/strong><\/br>\nControlla se il Gestore dei livelli presenta livelli nascosti o se il piano di taglio \u00e8 attivo su un livello specifico. Le prestazioni miglioreranno se non \u00e8 attivo nessun piano di taglio o se nessun livello \u00e8 nascosto nel Gestore dei livelli.\n<\/p>\n\n\n<p><strong>Evitare piani di ritaglio o sezioni di VisualARQ<\/strong><\/br>\nControlla se nel Gestore delle sezioni ci sono sezioni attive inutilmente. Non importa se la sezione taglia gli oggetti; quando una sezione \u00e8 attiva, le prestazioni possono essere compromesse. Lo stesso suggerimento si applica ai piani di ritaglio di Rhino.<\/p>\n\n<p><strong>Scegliere le impostazioni appropriate per la modalit\u00e0 di visualizzazione<\/strong><\/br>\n<em>Wireframe<\/em> e <\/em>Ombreggiata<\/em> sono modalit\u00e0 di visualizzazione pi\u00f9 veloci. Le modalit\u00e0 <em>Renderizzata<\/em>, <em>Penna<\/em>, <\/m>Artistico<\/em> o <em>Tecnico<\/em> riduce le prestazioni. Inoltre, anche l&#8217;attivazione delle ombre compromette le prestazioni.<\/p>\n\n<p><strong>Nascondere oggetti<\/strong><\/br>\nNascondi la geometria che non vuoi visualizzare mentre lavori a un progetto. Meno sono gli oggetti mostrati sulla vista, migliori saranno le prestazioni. Se la geometria \u00e8 organizzata in livelli, sar\u00e0 pi\u00f9 facile nasconderla e mostrarla attivando e disattivando i livelli.<\/p>\n\n<p><strong>Conoscere gli oggetti complessi<\/strong><\/br>\nLa geometria e gli oggetti free-form che presentano molte facce possono compromettere le prestazioni.<\/p>\n\n\n<p><strong>Mostrare solo una vista<\/strong><\/br>\nMostra solo una vista estesa mentre lavori anzich\u00e9 mostrare 4 o pi\u00f9 viste contemporaneamente. Rhino deve \u201cdisegnare\u201d la geometria indipendentemente su ciascuna vista, quindi il processo \u00e8 pi\u00f9 lento rispetto alla visualizzazione in una sola vista.<\/p>\n\n<p><strong>Usare impostazioni sulla qualit\u00e0 delle mesh di rendering pi\u00f9 veloci e scalettate.<\/strong><\/br>\nQualsiasi altra impostazione personalizzata pu\u00f2 fornire risultati migliori per le mesh, ma rallentando alcune operazioni durante la modellazione. L&#8217;opzione &#8220;Scalettate e pi\u00f9 veloce&#8221; dovrebbe fornire una qualit\u00e0 di modellazione e visualizzazione abbastanza adeguata. Questa impostazione pu\u00f2 essere regolata in Propriet\u00e0 del documento > Mesh.<\/p>\n\n<p><strong>Essere consapevoli della tolleranza assoluta per le unit\u00e0<\/strong><\/br>\nQuando si lavora a progetti architettonici, un valore ragionevole sarebbe compreso fra 1 o 0,1 millimetri per le unit\u00e0 documento di &#8220;tolleranza assoluta&#8221;. Qualsiasi altro valore inferiore forzer\u00e0 Rhino e VisualARQ a eseguire operazioni pi\u00f9 complesse e precise e ci\u00f2 pu\u00f2 compromettere notevolmente le prestazioni. Il valore di tolleranza assoluta dei modelli template di VisualARQ \u00e8 pari a 1 mm, ma pu\u00f2 essere diversa nei modelli template di Rhino. Questa impostazione pu\u00f2 essere regolata in Propriet\u00e0 del documento > Unit\u00e0.<\/p>\n\n<blockquote><strong>Nota<\/strong>: VisualARQ sfrutta le funzionalit\u00e0 di Rhino per gestire modelli di piccole e grandi dimensioni. L&#8217;utilizzo di VisualARQ nel modello non influenza le prestazioni, anche se le dimensioni del file possono aumentare fino a un 15% in pi\u00f9 rispetto al lavoro senza VisualARQ. In alcuni casi, i file dei modelli posso presentare dimensioni pi\u00f9 ridotte poich\u00e9 VisualARQ prova ad usare estrusioni dove possibile e rappresentare oggetti identici. Ad ogni modo, VisualARQ gestisce la geometria con i dati ed \u00e8 per questo che le dimensioni file possono cambiare leggermente in alcuni casi.\n\n<\/blockquote>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tipgroup":[70,167],"class_list":["post-25652","tip","type-tip","status-publish","hentry","tipgroup-files-it","tipgroup-workflow-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Suggerimenti per ottimizzare il flusso di lavoro con file di grandi dimensioni in Rhino - VisualARQ<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suggerimenti per ottimizzare il flusso di lavoro con file di grandi dimensioni in Rhino - VisualARQ\" \/>\n<meta property=\"og:description\" content=\"Per gestire file di grandi dimensioni in Rhino, puoi seguire alcuni dei seguenti suggerimenti che ti aiuteranno a ottimizzare il flusso di lavoro in Rhino e VisualARQ: Mostrare livelli e deselezionare il piano di taglio Controlla se il Gestore dei livelli presenta livelli nascosti o se il piano di taglio \u00e8 attivo su un livello [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stg.visualarq.com\/it\/support\/tip\/tips-to-streamline-the-workflow-with-large-files-in-rhino\/\" \/>\n<meta property=\"og:site_name\" content=\"VisualARQ\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/visualarq\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-17T11:14:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@VisualARQ\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/support\\\/tip\\\/tips-to-streamline-the-workflow-with-large-files-in-rhino\\\/\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/support\\\/tip\\\/tips-to-streamline-the-workflow-with-large-files-in-rhino\\\/\",\"name\":\"Suggerimenti per ottimizzare il flusso di lavoro con file di grandi dimensioni in Rhino - VisualARQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/#website\"},\"datePublished\":\"2022-02-08T14:52:09+00:00\",\"dateModified\":\"2022-05-17T11:14:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/support\\\/tip\\\/tips-to-streamline-the-workflow-with-large-files-in-rhino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/support\\\/tip\\\/tips-to-streamline-the-workflow-with-large-files-in-rhino\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/support\\\/tip\\\/tips-to-streamline-the-workflow-with-large-files-in-rhino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tips\",\"item\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/support\\\/tip\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Suggerimenti per ottimizzare il flusso di lavoro con file di grandi dimensioni in Rhino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/\",\"name\":\"VisualARQ\",\"description\":\"Flexible BIM for Rhino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stg.visualarq.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suggerimenti per ottimizzare il flusso di lavoro con file di grandi dimensioni in Rhino - VisualARQ","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Suggerimenti per ottimizzare il flusso di lavoro con file di grandi dimensioni in Rhino - VisualARQ","og_description":"Per gestire file di grandi dimensioni in Rhino, puoi seguire alcuni dei seguenti suggerimenti che ti aiuteranno a ottimizzare il flusso di lavoro in Rhino e VisualARQ: Mostrare livelli e deselezionare il piano di taglio Controlla se il Gestore dei livelli presenta livelli nascosti o se il piano di taglio \u00e8 attivo su un livello [&hellip;]","og_url":"https:\/\/stg.visualarq.com\/it\/support\/tip\/tips-to-streamline-the-workflow-with-large-files-in-rhino\/","og_site_name":"VisualARQ","article_publisher":"https:\/\/www.facebook.com\/visualarq","article_modified_time":"2022-05-17T11:14:36+00:00","twitter_card":"summary_large_image","twitter_site":"@VisualARQ","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stg.visualarq.com\/it\/support\/tip\/tips-to-streamline-the-workflow-with-large-files-in-rhino\/","url":"https:\/\/stg.visualarq.com\/it\/support\/tip\/tips-to-streamline-the-workflow-with-large-files-in-rhino\/","name":"Suggerimenti per ottimizzare il flusso di lavoro con file di grandi dimensioni in Rhino - VisualARQ","isPartOf":{"@id":"https:\/\/stg.visualarq.com\/it\/#website"},"datePublished":"2022-02-08T14:52:09+00:00","dateModified":"2022-05-17T11:14:36+00:00","breadcrumb":{"@id":"https:\/\/stg.visualarq.com\/it\/support\/tip\/tips-to-streamline-the-workflow-with-large-files-in-rhino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stg.visualarq.com\/it\/support\/tip\/tips-to-streamline-the-workflow-with-large-files-in-rhino\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stg.visualarq.com\/it\/support\/tip\/tips-to-streamline-the-workflow-with-large-files-in-rhino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stg.visualarq.com\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Tips","item":"https:\/\/stg.visualarq.com\/it\/support\/tip\/"},{"@type":"ListItem","position":3,"name":"Suggerimenti per ottimizzare il flusso di lavoro con file di grandi dimensioni in Rhino"}]},{"@type":"WebSite","@id":"https:\/\/stg.visualarq.com\/it\/#website","url":"https:\/\/stg.visualarq.com\/it\/","name":"VisualARQ","description":"Flexible BIM for Rhino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stg.visualarq.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/tip\/25652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/tip"}],"about":[{"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/types\/tip"}],"version-history":[{"count":0,"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/tip\/25652\/revisions"}],"wp:attachment":[{"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/media?parent=25652"}],"wp:term":[{"taxonomy":"tipgroup","embeddable":true,"href":"https:\/\/stg.visualarq.com\/it\/wp-json\/wp\/v2\/tipgroup?post=25652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}